{"id":98117,"date":"2022-12-21T12:25:04","date_gmt":"2022-12-21T17:25:04","guid":{"rendered":"https:\/\/www.aiu.edu\/areas-de-investigacao\/"},"modified":"2024-05-10T10:23:14","modified_gmt":"2024-05-10T14:23:14","slug":"areas-de-investigacao","status":"publish","type":"page","link":"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao\/","title":{"rendered":"\u00c1reas de investiga\u00e7\u00e3o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"98117\" class=\"elementor elementor-98117 elementor-40812\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ecab76e elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"ecab76e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc0298a\" data-id=\"dc0298a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c86dc48 elementor-widget elementor-widget-template\" data-id=\"c86dc48\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<header data-elementor-type=\"header\" data-elementor-id=\"27463\" class=\"elementor elementor-27463\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-95bf6a8 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"95bf6a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-db3587c e-con-full e-flex e-con e-child\" data-id=\"db3587c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ffe058 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"8ffe058\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"top_menu\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-8ffe058\" class=\"elementor-nav-menu\"><li class=\"sub-menu-columns menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-40613\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">About AIU<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40617\"><a href=\"https:\/\/www.aiu.edu\/about-us\/\" class=\"elementor-sub-item\">Sobre n\u00f3s<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40615\"><a href=\"https:\/\/www.aiu.edu\/general-information\/\" class=\"elementor-sub-item\">Informa\u00e7\u00f5es gerais<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40616\"><a href=\"https:\/\/www.aiu.edu\/missionvision\/\" class=\"elementor-sub-item\">Miss\u00e3o e vis\u00e3o<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40614\"><a href=\"https:\/\/www.aiu.edu\/faculty\/\" class=\"elementor-sub-item\">Docentes e funcion\u00e1rios<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40618\"><a href=\"https:\/\/www.aiu.edu\/accreditation\/\" class=\"elementor-sub-item\">Acredita\u00e7\u00e3o<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40620\"><a href=\"https:\/\/www.aiu.edu\/overview\/\" class=\"elementor-sub-item\">Vis\u00e3o geral<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40621\"><a href=\"https:\/\/www.aiu.edu\/representations\/\" class=\"elementor-sub-item\">Representa\u00e7\u00f5es<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-50118\"><a href=\"https:\/\/www.aiu.edu\/school-of-business-and-economics\/\" class=\"elementor-sub-item\">Escola de Gest\u00e3o e Economia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44791\"><a href=\"https:\/\/www.aiu.edu\/school-of-science-and-engineering\/\" class=\"elementor-sub-item\">Escola de Ci\u00eancias e Engenharia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44792\"><a href=\"https:\/\/www.aiu.edu\/school-of-social-and-human-studies\/\" class=\"elementor-sub-item\">Escola de Estudos Sociais e Humanos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44793\"><a href=\"https:\/\/www.aiu.edu\/program-goals\/\" class=\"elementor-sub-item\">Objectivos do programa<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44794\"><a href=\"https:\/\/www.aiu.edu\/unique-and-unrepeatable\/\" class=\"elementor-sub-item\">\u00danico e irrepet\u00edvel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44795\"><a href=\"https:\/\/www.aiu.edu\/andragogy-and-omniology\/\" class=\"elementor-sub-item\">Andragogia e Omniologia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44796\"><a href=\"https:\/\/www.aiu.edu\/academic-freedom-and-open-curriculum\/\" class=\"elementor-sub-item\">Liberdade acad\u00e9mica e curr\u00edculo aberto<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44797\"><a href=\"https:\/\/www.aiu.edu\/holistic-and-asynchronous\/\" class=\"elementor-sub-item\">Hol\u00edstico e ass\u00edncrono<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40636\"><a href=\"https:\/\/www.aiu.edu\/integral-culture\/\" class=\"elementor-sub-item\">Cultura Integral<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40637\"><a href=\"https:\/\/www.aiu.edu\/71st-human-rights-anniversary\/\" class=\"elementor-sub-item\">71\u00ba Anivers\u00e1rio dos Direitos Humanos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40638\"><a href=\"https:\/\/www.aiu.edu\/contact-us\/\" class=\"elementor-sub-item\">Contactar-nos<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"sub-menu-columns menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-40639\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Press Room<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44798\"><a href=\"https:\/\/www.aiu.edu\/aiu-blog\/\" class=\"elementor-sub-item\">Blogue da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40641\"><a href=\"https:\/\/www.aiu.edu\/aiu-news\/\" class=\"elementor-sub-item\">Not\u00edcias da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40642\"><a href=\"https:\/\/www.aiu.edu\/aiu-testimonials\/\" class=\"elementor-sub-item\">Testemunhos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40643\"><a href=\"https:\/\/www.aiu.edu\/student-publications\/\" class=\"elementor-sub-item\">Publica\u00e7\u00f5es de estudantes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44799\"><a href=\"https:\/\/www.aiu.edu\/media-center\/\" class=\"elementor-sub-item\">Centro multim\u00e9dia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-95284\"><a href=\"https:\/\/www.aiu.edu\/aiu-slides-collection\/\" class=\"elementor-sub-item\">Cole\u00e7\u00e3o de diapositivos da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40646\"><a target=\"_blank\" href=\"https:\/\/aiuvirtualgraduation.org\/\" class=\"elementor-sub-item\" rel=\"noopener\">Virtual Graduation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44801\"><a href=\"https:\/\/www.aiu.edu\/graduation-videos\/\" class=\"elementor-sub-item\">V\u00eddeos de gradua\u00e7\u00e3o da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44800\"><a href=\"https:\/\/www.aiu.edu\/aiu-campus-mundi-all-editions\/\" class=\"elementor-sub-item\">AIU Campus Mundi todas as edi\u00e7\u00f5es<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40649\"><a target=\"_blank\" href=\"https:\/\/myaiu.tv\/\" class=\"elementor-sub-item\" rel=\"noopener\">AIU TV<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40650\"><a target=\"_blank\" href=\"https:\/\/myaiuradio.org\/\" class=\"elementor-sub-item\" rel=\"noopener\">AIU Radio<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"sub-menu-columns menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-40651\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Admissions &#038; Students<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44802\"><a href=\"https:\/\/www.aiu.edu\/student-experience\/\" class=\"elementor-sub-item\">Experi\u00eancia do estudante<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44803\"><a href=\"https:\/\/www.aiu.edu\/community-social\/\" class=\"elementor-sub-item\">Comunidade Social<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44804\"><a href=\"https:\/\/www.aiu.edu\/support-for-your-online-study\/\" class=\"elementor-sub-item\">Apoio ao seu estudo em linha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44805\"><a href=\"https:\/\/www.aiu.edu\/academic-resources\/\" class=\"elementor-sub-item\">Recursos acad\u00e9micos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-59295\"><a target=\"_blank\" href=\"https:\/\/www.aiu.edu\/university\/np\/conferences\/live-classes.html\" class=\"elementor-sub-item\">Live Classes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44806\"><a href=\"https:\/\/www.aiu.edu\/webinars-and-conferences\/\" class=\"elementor-sub-item\">Webinars e confer\u00eancias<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44807\"><a href=\"https:\/\/www.aiu.edu\/distance-learning-and-online-courses\/\" class=\"elementor-sub-item\">Ensino \u00e0 dist\u00e2ncia e cursos em linha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44808\"><a href=\"https:\/\/www.aiu.edu\/career-center\/\" class=\"elementor-sub-item\">Centro de carreiras<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44809\"><a href=\"https:\/\/www.aiu.edu\/admissions\/\" class=\"elementor-sub-item\">Admiss\u00f5es<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-47607\"><a href=\"https:\/\/www.aiu.edu\/tuition\/\" class=\"elementor-sub-item\">Propinas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60473\"><a href=\"https:\/\/www.aiu.edu\/associates-programs\/\" class=\"elementor-sub-item\">Programas para associados<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60470\"><a href=\"https:\/\/www.aiu.edu\/bachelor-degree-programs\/\" class=\"elementor-sub-item\">Programas de licenciatura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60472\"><a href=\"https:\/\/www.aiu.edu\/masters-degree-programs\/\" class=\"elementor-sub-item\">Programas de mestrado<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60471\"><a href=\"https:\/\/www.aiu.edu\/doctorate-degree-programs\/\" class=\"elementor-sub-item\">Programas de doutoramento<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60474\"><a href=\"https:\/\/www.aiu.edu\/postdoctoral-research-program\/\" class=\"elementor-sub-item\">Programa de investiga\u00e7\u00e3o de p\u00f3s-doutoramento<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44811\"><a href=\"https:\/\/www.aiu.edu\/overview\/\" class=\"elementor-sub-item\">Vis\u00e3o geral<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44812\"><a href=\"https:\/\/www.aiu.edu\/aiu-testimonials\/\" class=\"elementor-sub-item\">Testemunhos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40663\"><a href=\"https:\/\/www.aiu.edu\/University\/np\/MyLifeIsASuccess\" class=\"elementor-sub-item\">AIU Success Stories<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44815\"><a href=\"https:\/\/www.aiu.edu\/faqs\/\" class=\"elementor-sub-item\">FAQ<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44814\"><a href=\"https:\/\/www.aiu.edu\/apply-online\/\" class=\"elementor-sub-item\">Candidatar-se online<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44087\"><a href=\"https:\/\/www.aiu.edu\/where-our-graduates-work\/\" class=\"elementor-sub-item\">Onde trabalham os nossos licenciados?<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8ffe058\" class=\"elementor-nav-menu\"><li class=\"sub-menu-columns menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-40613\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">About AIU<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40617\"><a href=\"https:\/\/www.aiu.edu\/about-us\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Sobre n\u00f3s<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40615\"><a href=\"https:\/\/www.aiu.edu\/general-information\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Informa\u00e7\u00f5es gerais<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40616\"><a href=\"https:\/\/www.aiu.edu\/missionvision\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Miss\u00e3o e vis\u00e3o<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40614\"><a href=\"https:\/\/www.aiu.edu\/faculty\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Docentes e funcion\u00e1rios<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40618\"><a href=\"https:\/\/www.aiu.edu\/accreditation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Acredita\u00e7\u00e3o<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40620\"><a href=\"https:\/\/www.aiu.edu\/overview\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vis\u00e3o geral<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40621\"><a href=\"https:\/\/www.aiu.edu\/representations\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Representa\u00e7\u00f5es<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-50118\"><a href=\"https:\/\/www.aiu.edu\/school-of-business-and-economics\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Escola de Gest\u00e3o e Economia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44791\"><a href=\"https:\/\/www.aiu.edu\/school-of-science-and-engineering\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Escola de Ci\u00eancias e Engenharia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44792\"><a href=\"https:\/\/www.aiu.edu\/school-of-social-and-human-studies\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Escola de Estudos Sociais e Humanos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44793\"><a href=\"https:\/\/www.aiu.edu\/program-goals\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Objectivos do programa<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44794\"><a href=\"https:\/\/www.aiu.edu\/unique-and-unrepeatable\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00danico e irrepet\u00edvel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44795\"><a href=\"https:\/\/www.aiu.edu\/andragogy-and-omniology\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Andragogia e Omniologia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44796\"><a href=\"https:\/\/www.aiu.edu\/academic-freedom-and-open-curriculum\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Liberdade acad\u00e9mica e curr\u00edculo aberto<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44797\"><a href=\"https:\/\/www.aiu.edu\/holistic-and-asynchronous\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hol\u00edstico e ass\u00edncrono<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40636\"><a href=\"https:\/\/www.aiu.edu\/integral-culture\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cultura Integral<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40637\"><a href=\"https:\/\/www.aiu.edu\/71st-human-rights-anniversary\/\" class=\"elementor-sub-item\" tabindex=\"-1\">71\u00ba Anivers\u00e1rio dos Direitos Humanos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40638\"><a href=\"https:\/\/www.aiu.edu\/contact-us\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Contactar-nos<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"sub-menu-columns menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-40639\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Press Room<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44798\"><a href=\"https:\/\/www.aiu.edu\/aiu-blog\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Blogue da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40641\"><a href=\"https:\/\/www.aiu.edu\/aiu-news\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Not\u00edcias da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40642\"><a href=\"https:\/\/www.aiu.edu\/aiu-testimonials\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Testemunhos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40643\"><a href=\"https:\/\/www.aiu.edu\/student-publications\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Publica\u00e7\u00f5es de estudantes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44799\"><a href=\"https:\/\/www.aiu.edu\/media-center\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Centro multim\u00e9dia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-95284\"><a href=\"https:\/\/www.aiu.edu\/aiu-slides-collection\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cole\u00e7\u00e3o de diapositivos da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40646\"><a target=\"_blank\" href=\"https:\/\/aiuvirtualgraduation.org\/\" class=\"elementor-sub-item\" tabindex=\"-1\" rel=\"noopener\">Virtual Graduation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44801\"><a href=\"https:\/\/www.aiu.edu\/graduation-videos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">V\u00eddeos de gradua\u00e7\u00e3o da AIU<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44800\"><a href=\"https:\/\/www.aiu.edu\/aiu-campus-mundi-all-editions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">AIU Campus Mundi todas as edi\u00e7\u00f5es<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40649\"><a target=\"_blank\" href=\"https:\/\/myaiu.tv\/\" class=\"elementor-sub-item\" tabindex=\"-1\" rel=\"noopener\">AIU TV<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40650\"><a target=\"_blank\" href=\"https:\/\/myaiuradio.org\/\" class=\"elementor-sub-item\" tabindex=\"-1\" rel=\"noopener\">AIU Radio<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"sub-menu-columns menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-40651\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Admissions &#038; Students<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44802\"><a href=\"https:\/\/www.aiu.edu\/student-experience\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Experi\u00eancia do estudante<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44803\"><a href=\"https:\/\/www.aiu.edu\/community-social\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Comunidade Social<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44804\"><a href=\"https:\/\/www.aiu.edu\/support-for-your-online-study\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Apoio ao seu estudo em linha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44805\"><a href=\"https:\/\/www.aiu.edu\/academic-resources\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Recursos acad\u00e9micos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-59295\"><a target=\"_blank\" href=\"https:\/\/www.aiu.edu\/university\/np\/conferences\/live-classes.html\" class=\"elementor-sub-item\" tabindex=\"-1\">Live Classes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44806\"><a href=\"https:\/\/www.aiu.edu\/webinars-and-conferences\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Webinars e confer\u00eancias<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44807\"><a href=\"https:\/\/www.aiu.edu\/distance-learning-and-online-courses\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ensino \u00e0 dist\u00e2ncia e cursos em linha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44808\"><a href=\"https:\/\/www.aiu.edu\/career-center\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Centro de carreiras<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44809\"><a href=\"https:\/\/www.aiu.edu\/admissions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Admiss\u00f5es<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-47607\"><a href=\"https:\/\/www.aiu.edu\/tuition\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Propinas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60473\"><a href=\"https:\/\/www.aiu.edu\/associates-programs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Programas para associados<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60470\"><a href=\"https:\/\/www.aiu.edu\/bachelor-degree-programs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Programas de licenciatura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60472\"><a href=\"https:\/\/www.aiu.edu\/masters-degree-programs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Programas de mestrado<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60471\"><a href=\"https:\/\/www.aiu.edu\/doctorate-degree-programs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Programas de doutoramento<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-60474\"><a href=\"https:\/\/www.aiu.edu\/postdoctoral-research-program\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Programa de investiga\u00e7\u00e3o de p\u00f3s-doutoramento<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44811\"><a href=\"https:\/\/www.aiu.edu\/overview\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vis\u00e3o geral<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44812\"><a href=\"https:\/\/www.aiu.edu\/aiu-testimonials\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Testemunhos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-40663\"><a href=\"https:\/\/www.aiu.edu\/University\/np\/MyLifeIsASuccess\" class=\"elementor-sub-item\" tabindex=\"-1\">AIU Success Stories<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44815\"><a href=\"https:\/\/www.aiu.edu\/faqs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">FAQ<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44814\"><a href=\"https:\/\/www.aiu.edu\/apply-online\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Candidatar-se online<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-44087\"><a href=\"https:\/\/www.aiu.edu\/where-our-graduates-work\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Onde trabalham os nossos licenciados?<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-297534f e-con-full e-flex e-con e-child\" data-id=\"297534f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e81da7 elementor-widget elementor-widget-text-editor\" data-id=\"9e81da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<a title=\"Student Login\" href=\"https:\/\/www.aiu.edu\/aiu-login\/login.html\" target=\"_blank\" rel=\"noopener\">Student Login<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33343f0 e-con-full e-flex e-con e-child\" data-id=\"33343f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76456db elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"76456db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpml-elementor-ls\">\n<div\n\t role=\"navigation\" aria-label=\"Alternador de Idioma\" class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-dropdown js-wpml-ls-legacy-dropdown\">\n\t<ul>\n\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-pt wpml-ls-current-language wpml-ls-item-legacy-dropdown\">\n\t\t\t\t\t\t\t\t\t<a href=\"#\" hreflang=\"pt-pt\" lang=\"pt-pt\" class=\"js-wpml-ls-item-toggle wpml-ls-item-toggle\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-default\" aria-label=\"Portugu\u00eas \u2013 Language switcher, press tab to navigate to other languages\" title=\"Switch to Portugu\u00eas\">\n\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-pt.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">Portugu\u00eas<\/span><\/a>\n\n\t\t\t<ul id=\"wpml-ls-submenu-default\" class=\"wpml-ls-sub-menu\">\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/\" hreflang=\"en\" lang=\"en\" class=\"wpml-ls-link\" aria-label=\"Switch to English\" title=\"Switch to English\">\n\t\t\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/flags\/555526.png\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">English<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/es\/\" hreflang=\"es\" lang=\"es\" class=\"wpml-ls-link\" aria-label=\"Switch to Espa\u00f1ol\" title=\"Switch to Espa\u00f1ol\">\n\t\t\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">Espa\u00f1ol<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr wpml-ls-last-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/fr\/\" hreflang=\"fr\" lang=\"fr\" class=\"wpml-ls-link\" aria-label=\"Switch to Fran\u00e7ais\" title=\"Switch to Fran\u00e7ais\">\n\t\t\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">Fran\u00e7ais<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/li>\n\n\t<\/ul>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d92d0f3 e-con-full e-flex e-con e-child\" data-id=\"d92d0f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6bf369 e-con-full e-flex e-con e-child\" data-id=\"e6bf369\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50952ad elementor-widget elementor-widget-image\" data-id=\"50952ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"560\" height=\"230\" src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/09\/logo-AIU.gif\" class=\"attachment-large size-large wp-image-105887\" alt=\"\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4c6fe2 e-con-full e-flex e-con e-child\" data-id=\"a4c6fe2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fbce3a1 bdt-mega-menu-hamburger-m elementor-widget elementor-widget-bdt-mega-menu\" data-id=\"fbce3a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ep_megamenu_mode&quot;:&quot;click&quot;,&quot;ep_megamenu_direction&quot;:&quot;horizontal&quot;,&quot;ep_megamenu_offset&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;ep_megamenu_offset_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;ep_megamenu_animation_type&quot;:&quot;bdt-animation-fade&quot;,&quot;ep_megamenu_animation_duration&quot;:200}\" data-widget_type=\"bdt-mega-menu.default\">\n\t\t\t\t\t            <div class=\"ep-megamenu initialized ep-megamenu-horizontal\">\n                <div class=\"megamenu-header-default\">\n                    <ul id=\"ep-megamenu-fbce3a1\" class=\"bdt-navbar-nav \"><li id=\"menu-item-120668\" class=\"mega_first_child menu-item menu-item-type-custom menu-item-object-custom menu-item-120668 nav-item ep-has-megamenu\"data-width-type=\"full\"><a class=\"ep-menu-nav-link\" href=\"#\">RESEARCH<i class=\"bdt-megamenu-indicator ep-icon-arrow-down-3\"><\/i><\/a><ul class=\"ep-megamenu-panel bdt-drop\"><style>.elementor-120672 .elementor-element.elementor-element-a55db51 > .elementor-container > .elementor-row{align-items:stretch;}.elementor-120672 .elementor-element.elementor-element-a55db51:not(.elementor-motion-effects-element-type-background), .elementor-120672 .elementor-element.elementor-element-a55db51 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#02010100;}.elementor-120672 .elementor-element.elementor-element-a55db51{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120672 .elementor-element.elementor-element-a55db51 > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120672 .elementor-element.elementor-element-036a036:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120672 .elementor-element.elementor-element-036a036 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(90deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120672 .elementor-element.elementor-element-036a036 > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120672 .elementor-element.elementor-element-036a036 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-mega-menu-inner-links{grid-template-columns:repeat(1, minmax(0, 1fr));gap:7px;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-link-item{flex-direction:row;justify-content:flex-start;align-items:center;gap:15px;text-align:inherit;padding:0px 0px 0px 19px;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-graphic-element{width:42px;height:42px;background-color:#a0a0a0;margin-top:0px;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-graphic-element img{width:42px;height:42px;object-fit:cover;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-graphic-element,.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-graphic-element img{border-radius:100px 100px 100px 100px;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-ge-icon{color:#ffffff;font-size:15px;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-ge-text{color:#ffffff;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-title{color:#2c2c2c;font-size:15px;font-weight:bold;margin-top:0px;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-link-item:hover .ue-title{color:var( --e-global-color-primary );}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-text{color:#090909;margin-top:0px;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-item-separator{border-bottom-style:solid;border-bottom-width:1px;border-bottom-color:#d9d9d9;}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-menu-title{color:#000000;text-align:inherit;}.elementor-120672 .elementor-element.elementor-element-ae2e501 > .elementor-widget-container{padding:5px 5px 5px 5px;}.elementor-120672 .elementor-element.elementor-element-e10af69:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120672 .elementor-element.elementor-element-e10af69 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(280deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120672 .elementor-element.elementor-element-e10af69 > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120672 .elementor-element.elementor-element-e10af69 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120672 .elementor-element.elementor-element-05b049a{--spacer-size:235px;margin:5px 5px calc(var(--kit-widget-spacing, 0px) + 5px) 5px;background-image:url(\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2024\/08\/inner_banner.jpg\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-120672 .elementor-element.elementor-element-a6c8855{font-size:12px;font-weight:400;color:#000000;padding:5px 5px 5px 5px;}.elementor-widget .tippy-tooltip .tippy-content{text-align:center;}@media(min-width:768px){.elementor-120672 .elementor-element.elementor-element-036a036{width:50%;}.elementor-120672 .elementor-element.elementor-element-e10af69{width:50%;}}@media(max-width:1024px){.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-mega-menu-inner-links{grid-template-columns:repeat(2, minmax(0, 1fr));}.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-link-item{gap:12px;}}@media(max-width:767px){.elementor-120672 .elementor-element.elementor-element-ae2e501 .ue-mega-menu-inner-links{grid-template-columns:repeat(1, minmax(0, 1fr));}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"120672\" class=\"elementor elementor-120672\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"ep_megamenu_content\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a55db51 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"a55db51\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-036a036\" data-id=\"036a036\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae2e501 elementor-widget elementor-widget-ucaddon_mega_menu_inner_links\" data-id=\"ae2e501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_mega_menu_inner_links.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Mega Menu Inner Links -->\n<style>\/* widget: Mega Menu Inner Links *\/\n\n#uc_mega_menu_inner_links_elementor_ae2e501\n{\n  display:grid;\n}\n\n#uc_mega_menu_inner_links_elementor_ae2e501 .ue-link-item\n{\n  display:flex;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_ae2e501 .ue-graphic-element\n{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  overflow:hidden;\n  flex-grow:0;\n  flex-shrink:0;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_ae2e501 .ue-graphic-element svg\n{\n  height:1em;\n  width:1em;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_ae2e501 .ue-graphic-element img\n{\n  display:block;\n}\n\n#uc_mega_menu_inner_links_elementor_ae2e501 .ue-title, #uc_mega_menu_inner_links_elementor_ae2e501 .ue-text\n{\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_ae2e501 .ue-ge-image\n{\n  width:100%;\n  transition:0.3s;\n}\n\n<\/style>\n\n\n<div class=\"ue-mega-menu-inner-links\" id=\"uc_mega_menu_inner_links_elementor_ae2e501\">\n  <div class=\"elementor-repeater-item-3a915ba\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/research-areas\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Research Areas<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-f738dcf\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/aiu-reshaping-artificial-intelligence-in-higher-education\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Artificial Intelligence<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-b7cccb5\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/atlantic-international-university-webinars\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Webinars<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-d1521c8\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/webinars-and-conferences\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Conferences & Symposiums<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-86f0346\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/aiu-dissertation-defense\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Thesis Dissertation Defense<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-3a8abad\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/academic-publication\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Academic Publications<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-7266679\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/mentors-and-academic-advisors\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Mentors & Academic Advisors<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-669d484\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/grants-and-peer-review\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Grants & Peer Review<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-2a1659f\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/online-library\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Online Library<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-f301ae7\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/virtual-labs\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Virtual Labs<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n <\/div>\n<!-- end Mega Menu Inner Links -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e10af69\" data-id=\"e10af69\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05b049a elementor-widget elementor-widget-spacer\" data-id=\"05b049a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c8855 elementor-widget elementor-widget-text-editor\" data-id=\"a6c8855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDistance Learning at AIU is enhanced by vast academic resources and innovative technologies build into the Virtual Campus: Hundreds of self-paced courses with video lectures and step by step lessons, thousands of optional assignments, 140,000 e-books, the Social Media &#038; Networking platform allowing collaboration\/chat\/communications between students, and MYAIU develop students holistically in 11 areas beyond just academics.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/ul><\/li>\n<li id=\"menu-item-120669\" class=\"don_menu menu-item menu-item-type-custom menu-item-object-custom menu-item-120669 nav-item ep-has-megamenu\"data-width-type=\"full\"><a class=\"ep-menu-nav-link\" href=\"#\">PROGRAMS OFFERED<i class=\"bdt-megamenu-indicator ep-icon-arrow-down-3\"><\/i><\/a><ul class=\"ep-megamenu-panel bdt-drop\"><style>.elementor-120678 .elementor-element.elementor-element-016cba8 > .elementor-container > .elementor-row{align-items:stretch;}.elementor-120678 .elementor-element.elementor-element-016cba8:not(.elementor-motion-effects-element-type-background), .elementor-120678 .elementor-element.elementor-element-016cba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#02010100;}.elementor-120678 .elementor-element.elementor-element-016cba8{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120678 .elementor-element.elementor-element-016cba8 > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120678 .elementor-element.elementor-element-6c224c5:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120678 .elementor-element.elementor-element-6c224c5 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(90deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120678 .elementor-element.elementor-element-6c224c5 > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120678 .elementor-element.elementor-element-6c224c5 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120678 .elementor-element.elementor-element-6184707:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120678 .elementor-element.elementor-element-6184707 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(280deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120678 .elementor-element.elementor-element-6184707 > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120678 .elementor-element.elementor-element-6184707 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120678 .elementor-element.elementor-element-a94dd91{--spacer-size:235px;margin:5px 5px calc(var(--kit-widget-spacing, 0px) + 5px) 5px;padding:0px 0px 0px 0px;background-image:url(\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/09\/AIU_2018First-387-1-1.jpg\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-120678 .elementor-element.elementor-element-4793b02{font-size:12px;font-weight:400;color:#000000;padding:5px 5px 5px 5px;}.elementor-widget .tippy-tooltip .tippy-content{text-align:center;}@media(min-width:768px){.elementor-120678 .elementor-element.elementor-element-6c224c5{width:50%;}.elementor-120678 .elementor-element.elementor-element-6184707{width:50%;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"120678\" class=\"elementor elementor-120678\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"ep_megamenu_content\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-016cba8 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"016cba8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c224c5\" data-id=\"6c224c5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-595d5d6 elementor-widget elementor-widget-shortcode\" data-id=\"595d5d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"submenu-wrapper\"><ul class=\"submenu\"><li><a href=\"https:\/\/www.aiu.edu\/areas-of-study\/\">Areas of Study<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/course-curriculum\/\">Courses and Curriculum<\/a><\/li><li><a href=\"https:\/\/courses.aiu.edu\/\" target=\"_blank\" rel=\"noopener\">Open Courses<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/register-for-a-program\/\">Register for a Program<\/a><\/li><li class=\"menu-item-has-children\"><a href=\"#\">Associate Program<\/a><div class=\"submenu-wrapper\"><ul class=\"submenu\"><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-addiction-counseling\/\">Associate in Addiction Counseling<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-agriculture-food-and-resources\/\">Associate in Agriculture Food And Resources<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-anti-terrorism-security\/\">Associate in Anti Terrorism Security<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-behavior-analysis-in-special-education\/\">Associate in Behavior Analysis In Special Education<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-bioethics\/\">Associate in Bioethics<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-climatology\/\">Associate in Climatology<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-cultural-theological-communication\/\">Associate in Cultural Theological Communication<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-culinary-arts\/\">Associate in Culinary Arts<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/associate-in-ecotechnology\/\">Associate in Ecotechnology<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/associates-programs\/\">View all Associates Programs<\/a><\/li><\/ul><\/div><\/li><li class=\"menu-item-has-children\"><a href=\"#\">Bachelor Program<\/a><div class=\"submenu-wrapper\"><ul class=\"submenu\"><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelors-in-community-development\/\">Bachelors in Community Development<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelor-in-environmental-science\/\">Bachelors in Environmental Science<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelor-in-education-b-ed-bs\/\">Bachelor in Education (B.Ed, BS)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelor-of-economics\/\">Bachelors in Economics<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelors-in-entrepreneurship\/\">Bachelors in Entrepreneurship<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelors-in-financial-administration\/\">Bachelors in Financial Administration<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelor-of-human-resources-management\/\">Bachelors in Human Resource Management<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelor-in-linguistics\/\">Bachelors in Linguistics<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelors-in-nutritional-science\/\">Bachelors in Nutritional Science<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelors-in-occupational-health-and-safety\/\">Bachelors in Occupational Health and Safety<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/bachelors-in-psychology\/\">Bachelors in Psychology<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/bachelor-degree-programs\/\">View all Bachelor Programs<\/a><\/li><\/ul><\/div><\/li><li class=\"menu-item-has-children\"><a href=\"#\">Doctorate Program<\/a><div class=\"submenu-wrapper\"><ul class=\"submenu\"><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-biology-phd\/\">Doctor | of Biology (PhD)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-business-administration-dba-phd\/\">Doctorate in Business Administration (DBA, PhD)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-economics-phd\/\">Doctor of Economics (PhD)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-electrical-engineering-d-sc-phd\/\">Doctor of Electrical Engineering (D.Sc, PhD)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-finance-phd\/\">Doctor of Finance (PhD)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-international-relations\/\">Doctorate in International Relations<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-information-technology-d-sc\/\">Doctorate in Information Technology (D.Sc)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-legal-studies-phd\/\">Doctor of Legal Studies (PhD)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-project-management-phd\/\">Doctor of Project Management (PhD)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctor-of-sociology-phd-d-sc\/\">Doctor of Sociology (PhD, D.Sc)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/doctorate-in-sustainable-natural-resources-management\/\">Doctorate in Sustainable Natural Resources Management<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/doctorate-degree-programs\/\">View all Doctorate Programs<\/a><\/li><\/ul><\/div><\/li><li class=\"menu-item-has-children\"><a href=\"#\">Master Program<\/a><div class=\"submenu-wrapper\"><ul class=\"submenu\"><li><a href=\"https:\/\/www.aiu.edu\/program\/master-in-autonomous-vehicle-technology\/\">Master in Autonomous Vehicle Technology<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/master-of-business-administration\/\">Masters in Business Administration<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/masters-in-civil-engineering\/\">Masters in Civil Engineering<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/master-of-construction-management\/\">Master of Construction Management<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/master-of-hydrology-ms\/\">Master of Hydrology (MS)<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/master-of-mechanical-engineering-ms\/\">Masters in Mechanical Engineering<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/master-in-nutrition\/\">Masters in Nutrition<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/master-of-science-in-educational-administration-ms\/\">Masters of science in Educational Administration<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/masters-degree-programs\/\">View all Masters Programs<\/a><\/li><\/ul><\/div><\/li><li class=\"menu-item-has-children\"><a href=\"#\">Postdoctoral Program<\/a><div class=\"submenu-wrapper\"><ul class=\"submenu\"><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-animal-science\/\">Postdoctoral in Animal Science<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-anti-terrorism-security\/\">Postdoctoral in Anti Terrorism Security<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-behavior-analysis-in-special-education\/\">Postdoctoral in Behavior Analysis In Special Education<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-bioethics\/\">Postdoctoral in Bioethics<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-blockchain-technology-and-digital-currency\/\">Postdoctoral in Blockchain Technology and Digital Currency<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-business-management\/\">Postdoctoral in Business Management<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-cloud-computing\/\">Postdoctoral in Cloud Computing<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/program\/postdoctoral-in-computer-engineering\/\">Postdoctoral in Computer Engineering<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/postdoctoral-research-program\/\">View all Postdoctoral Programs<\/a><\/li><\/ul><\/div><\/li><\/ul><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6184707\" data-id=\"6184707\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a94dd91 elementor-widget elementor-widget-spacer\" data-id=\"a94dd91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4793b02 elementor-widget elementor-widget-text-editor\" data-id=\"4793b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAIU offers a wide range of majors in areas including the Arts, Business, Science, Technology, Social, and Human studies. More than 120 degrees and programs are available for adult learners at the associate\u2019s, bachelor\u2019s, master\u2019s, doctoral and postdoctoral level.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/ul><\/li>\n<li id=\"menu-item-120670\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-120670 nav-item ep-has-megamenu\"data-width-type=\"full\"><a class=\"ep-menu-nav-link\" href=\"#\">VIRTUAL CAMPUS<i class=\"bdt-megamenu-indicator ep-icon-arrow-down-3\"><\/i><\/a><ul class=\"ep-megamenu-panel bdt-drop\"><style>.elementor-120685 .elementor-element.elementor-element-8e2b845 > .elementor-container > .elementor-row{align-items:stretch;}.elementor-120685 .elementor-element.elementor-element-8e2b845:not(.elementor-motion-effects-element-type-background), .elementor-120685 .elementor-element.elementor-element-8e2b845 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#02010100;}.elementor-120685 .elementor-element.elementor-element-8e2b845{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120685 .elementor-element.elementor-element-8e2b845 > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120685 .elementor-element.elementor-element-34a7eab:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120685 .elementor-element.elementor-element-34a7eab > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(90deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120685 .elementor-element.elementor-element-34a7eab > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120685 .elementor-element.elementor-element-34a7eab > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-mega-menu-inner-links{grid-template-columns:repeat(1, minmax(0, 1fr));gap:7px;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-link-item{flex-direction:row;justify-content:flex-start;align-items:center;gap:15px;text-align:inherit;padding:0px 0px 0px 19px;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-graphic-element{width:42px;height:42px;background-color:#a0a0a0;margin-top:0px;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-graphic-element img{width:42px;height:42px;object-fit:cover;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-graphic-element,.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-graphic-element img{border-radius:100px 100px 100px 100px;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-ge-icon{color:#ffffff;font-size:15px;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-ge-text{color:#ffffff;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-title{color:#2c2c2c;font-size:15px;font-weight:bold;margin-top:0px;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-link-item:hover .ue-title{color:var( --e-global-color-primary );}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-text{color:#090909;margin-top:0px;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-item-separator{border-bottom-style:solid;border-bottom-width:1px;border-bottom-color:#d9d9d9;}.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-menu-title{color:#000000;text-align:inherit;}.elementor-120685 .elementor-element.elementor-element-e9f364a > .elementor-widget-container{padding:5px 5px 5px 5px;}.elementor-120685 .elementor-element.elementor-element-0a14afa:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120685 .elementor-element.elementor-element-0a14afa > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(280deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120685 .elementor-element.elementor-element-0a14afa > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120685 .elementor-element.elementor-element-0a14afa > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120685 .elementor-element.elementor-element-14c9063{--spacer-size:235px;margin:5px 5px calc(var(--kit-widget-spacing, 0px) + 5px) 5px;padding:0px 0px 0px 0px;background-image:url(\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/09\/inner39-1.webp\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-120685 .elementor-element.elementor-element-c955ed2{font-size:12px;font-weight:400;color:#000000;padding:5px 5px 5px 5px;}.elementor-widget .tippy-tooltip .tippy-content{text-align:center;}@media(min-width:768px){.elementor-120685 .elementor-element.elementor-element-34a7eab{width:50%;}.elementor-120685 .elementor-element.elementor-element-0a14afa{width:50%;}}@media(max-width:1024px){.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-mega-menu-inner-links{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media(max-width:767px){.elementor-120685 .elementor-element.elementor-element-e9f364a .ue-mega-menu-inner-links{grid-template-columns:repeat(1, minmax(0, 1fr));}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"120685\" class=\"elementor elementor-120685\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"ep_megamenu_content\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e2b845 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"8e2b845\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34a7eab\" data-id=\"34a7eab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9f364a elementor-widget elementor-widget-ucaddon_mega_menu_inner_links\" data-id=\"e9f364a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_mega_menu_inner_links.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Mega Menu Inner Links -->\n<style>\/* widget: Mega Menu Inner Links *\/\n\n#uc_mega_menu_inner_links_elementor_e9f364a\n{\n  display:grid;\n}\n\n#uc_mega_menu_inner_links_elementor_e9f364a .ue-link-item\n{\n  display:flex;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_e9f364a .ue-graphic-element\n{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  overflow:hidden;\n  flex-grow:0;\n  flex-shrink:0;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_e9f364a .ue-graphic-element svg\n{\n  height:1em;\n  width:1em;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_e9f364a .ue-graphic-element img\n{\n  display:block;\n}\n\n#uc_mega_menu_inner_links_elementor_e9f364a .ue-title, #uc_mega_menu_inner_links_elementor_e9f364a .ue-text\n{\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_e9f364a .ue-ge-image\n{\n  width:100%;\n  transition:0.3s;\n}\n\n<\/style>\n\n\n<div class=\"ue-mega-menu-inner-links\" id=\"uc_mega_menu_inner_links_elementor_e9f364a\">\n  <div class=\"elementor-repeater-item-b7cccb5\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/aiu-virtual-campus\/\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Virtual Campus<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-3a915ba\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/university\/np\/conferences\/archives.html\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Live Classes<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-f892787\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/mini-courses\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Mini Courses<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-f738dcf\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/features-and-tools\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Features & Tools<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-d1521c8\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/mobile-app\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Mobile APP<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-f935c4f\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/social-media-center-aiu-link\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Social Media Center (AIU Link)<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-4df67a0\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/merlin-media-center\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Merlin Media Center<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-40cde77\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/games-and-events\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Games & Events<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-2ee779b\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/online-library\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Online Library<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-c5977a6\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/curriculum-builder-tool\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Curriculum Builder<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-a78afe9\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/language-center\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Language Center<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-f020052\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/site-builder\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Site Builder<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-47b8596\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/myaiu\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">MYAIU<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n <\/div>\n<!-- end Mega Menu Inner Links -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0a14afa\" data-id=\"0a14afa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14c9063 elementor-widget elementor-widget-spacer\" data-id=\"14c9063\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c955ed2 elementor-widget elementor-widget-text-editor\" data-id=\"c955ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Distance Learning at AIU is enhanced by vast academic resources and innovative technologies build into the Virtual Campus: Hundreds of self-paced courses with video lectures and step by step lessons, thousands of optional assignments, 140,000 e-books, the Social Media &amp; Networking platform allowing collaboration\/chat\/communications between students, and MYAIU develop students holistically in 11 areas beyond just academics.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/ul><\/li>\n<li id=\"menu-item-120671\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-120671 nav-item ep-has-megamenu\"data-width-type=\"full\"><a class=\"ep-menu-nav-link\" href=\"#\">ALUMNI<i class=\"bdt-megamenu-indicator ep-icon-arrow-down-3\"><\/i><\/a><ul class=\"ep-megamenu-panel bdt-drop\"><style>.elementor-120689 .elementor-element.elementor-element-729afea > .elementor-container > .elementor-row{align-items:stretch;}.elementor-120689 .elementor-element.elementor-element-729afea:not(.elementor-motion-effects-element-type-background), .elementor-120689 .elementor-element.elementor-element-729afea > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#02010100;}.elementor-120689 .elementor-element.elementor-element-729afea{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120689 .elementor-element.elementor-element-729afea > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120689 .elementor-element.elementor-element-ad75779:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120689 .elementor-element.elementor-element-ad75779 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(90deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120689 .elementor-element.elementor-element-ad75779 > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120689 .elementor-element.elementor-element-ad75779 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-mega-menu-inner-links{grid-template-columns:repeat(1, minmax(0, 1fr));gap:7px;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-link-item{flex-direction:row;justify-content:flex-start;align-items:center;gap:15px;text-align:inherit;padding:0px 0px 0px 19px;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-graphic-element{width:42px;height:42px;background-color:#a0a0a0;margin-top:0px;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-graphic-element img{width:42px;height:42px;object-fit:cover;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-graphic-element,.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-graphic-element img{border-radius:100px 100px 100px 100px;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-ge-icon{color:#ffffff;font-size:15px;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-ge-text{color:#ffffff;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-title{color:#2c2c2c;font-size:15px;font-weight:bold;margin-top:0px;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-link-item:hover .ue-title{color:var( --e-global-color-primary );}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-text{color:#090909;margin-top:0px;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-item-separator{border-bottom-style:solid;border-bottom-width:1px;border-bottom-color:#d9d9d9;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-menu-title{color:#000000;text-align:inherit;}.elementor-120689 .elementor-element.elementor-element-cd5dee2 > .elementor-widget-container{padding:5px 5px 5px 5px;}.elementor-120689 .elementor-element.elementor-element-ec61411:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-120689 .elementor-element.elementor-element-ec61411 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(280deg, #EAEDF1 37%, #FFFFFF 86%);}.elementor-120689 .elementor-element.elementor-element-ec61411 > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-120689 .elementor-element.elementor-element-ec61411 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-120689 .elementor-element.elementor-element-591b4f5{--spacer-size:235px;margin:5px 5px calc(var(--kit-widget-spacing, 0px) + 5px) 5px;padding:0px 0px 0px 0px;background-image:url(\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2024\/03\/graduation6.webp\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-120689 .elementor-element.elementor-element-eb1cc79{font-size:12px;font-weight:400;color:#000000;margin:0px 0px calc(var(--kit-widget-spacing, 0px) + 5px) 0px;padding:5px 5px 5px 5px;}.elementor-widget .tippy-tooltip .tippy-content{text-align:center;}@media(min-width:768px){.elementor-120689 .elementor-element.elementor-element-ad75779{width:50%;}.elementor-120689 .elementor-element.elementor-element-ec61411{width:50%;}}@media(max-width:1024px){.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-mega-menu-inner-links{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media(max-width:767px){.elementor-120689 .elementor-element.elementor-element-cd5dee2 .ue-mega-menu-inner-links{grid-template-columns:repeat(1, minmax(0, 1fr));}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"120689\" class=\"elementor elementor-120689\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"ep_megamenu_content\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-729afea elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"729afea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ad75779\" data-id=\"ad75779\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd5dee2 elementor-widget elementor-widget-ucaddon_mega_menu_inner_links\" data-id=\"cd5dee2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_mega_menu_inner_links.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Mega Menu Inner Links -->\n<style>\/* widget: Mega Menu Inner Links *\/\n\n#uc_mega_menu_inner_links_elementor_cd5dee2\n{\n  display:grid;\n}\n\n#uc_mega_menu_inner_links_elementor_cd5dee2 .ue-link-item\n{\n  display:flex;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_cd5dee2 .ue-graphic-element\n{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  overflow:hidden;\n  flex-grow:0;\n  flex-shrink:0;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_cd5dee2 .ue-graphic-element svg\n{\n  height:1em;\n  width:1em;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_cd5dee2 .ue-graphic-element img\n{\n  display:block;\n}\n\n#uc_mega_menu_inner_links_elementor_cd5dee2 .ue-title, #uc_mega_menu_inner_links_elementor_cd5dee2 .ue-text\n{\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_mega_menu_inner_links_elementor_cd5dee2 .ue-ge-image\n{\n  width:100%;\n  transition:0.3s;\n}\n\n<\/style>\n\n\n<div class=\"ue-mega-menu-inner-links\" id=\"uc_mega_menu_inner_links_elementor_cd5dee2\">\n  <div class=\"elementor-repeater-item-b7cccb5\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/aiu-alumni-association\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Alumni Association<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-3a915ba\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/graduation-videos\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Graduation Videos<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-75c8da1\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/graduates\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Graduates<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-d9e2e7b\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/outstanding-students\/\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Outstanding Students<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-1284c17\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/University\/np\/MyLifeIsASuccess\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Success Stories<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-bef31ce\">\n<a class=\"ue-link-item\" href=\"https:\/\/www.aiu.edu\/sponsors\" target=\"_blank\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Sponsors<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n<div class=\"elementor-repeater-item-d2a98d6\">\n<a class=\"ue-link-item\" href=\"https:\/\/admin2.aiu.edu\/ApplicationManagers\/GraduateDirectory\" target=\"_blank\" rel=\"noopener\">\n                    <div class=\"ue-link-item-content\">\n    <div class=\"ue-link-item-title ue-title\">Graduates Directory<\/div>\t\n      <\/div>\n<\/a>\n\n<div class=\"ue-item-separator\"><\/div>\n<\/div>\n <\/div>\n<!-- end Mega Menu Inner Links -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ec61411\" data-id=\"ec61411\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-591b4f5 elementor-widget elementor-widget-spacer\" data-id=\"591b4f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb1cc79 elementor-widget elementor-widget-text-editor\" data-id=\"eb1cc79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>The world is YOUR campus!\u201d, that is the message of AIU\u2019s month magazine Campus Mundi. Hear the voices and see the faces that make up AIU. Campus Mundi brings the world of AIU to you every months with inspirational stories, news and achievements by AIU members from around the world (students and staff are located in over 200 countries).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/ul><\/li>\n<\/ul>\n                <\/div>\n                <div class=\"megamenu-header-mobile\" style=\"display: none;\">\n                    <a href=\"javascript:void(0);\" class=\"bdt-navbar-toggle\" aria-label=\"Toggle Menu\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-list\" viewBox=\"0 0 16 16\">\n                            <path fill-rule=\"evenodd\" d=\"M2.5 12a.5.5 0 0 1 .5-.5h10a.5.5 0 0 1 0 1H3a.5.5 0 0 1-.5-.5zm0-4a.5.5 0 0 1 .5-.5h10a.5.5 0 0 1 0 1H3a.5.5 0 0 1-.5-.5zm0-4a.5.5 0 0 1 .5-.5h10a.5.5 0 0 1 0 1H3a.5.5 0 0 1-.5-.5z\" \/>\n                        <\/svg>\n\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" viewBox=\"0 0 16 16\">\n                            <path fill-rule=\"evenodd\" d=\"M4.646 4.646a.5.5 0 0 1 .708 0L8 7.293l2.646-2.647a.5.5 0 0 1 .708.708L8.707 8l2.647 2.646a.5.5 0 0 1-.708.708L8 8.707l-2.646 2.647a.5.5 0 0 1-.708-.708L7.293 8 4.646 5.354a.5.5 0 0 1 0-.708z\"\/>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n\n\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4f1615 elementor-align-center elementor-widget elementor-widget-tm-button\" data-id=\"f4f1615\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-button-wrapper\">\n\t\t\t<a href=\"https:\/\/rep.aiu.edu\/ApplyFormHTML\/ApplyFormAIN.aspx\" target=\"_blank\" class=\"tm-button-link tm-button style-flat tm-button-nm\" role=\"button\">\n\t\t\t\t\t\t<div class=\"button-content-wrapper\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"button-text\">APPLY NOW<\/span>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d60b4c3 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"d60b4c3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0c3777c e-con-full e-flex e-con e-child\" data-id=\"0c3777c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa1004e elementor-widget elementor-widget-image\" data-id=\"aa1004e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"560\" height=\"230\" src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/09\/logo-AIU.gif\" class=\"attachment-full size-full wp-image-105887\" alt=\"\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11b1ad6 e-con-full e-flex e-con e-child\" data-id=\"11b1ad6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8649c87 elementor-widget elementor-widget-ucaddon_ue_side_menu\" data-id=\"8649c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_ue_side_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Side Menu -->\n<style>\/* widget: Side Menu *\/\n\n#uc_ue_side_menu_elementor_8649c87 *\n{\n  box-sizing:border-box;\n  -webkit-box-sizing: border-box;\n  -moz-box-sizing: border-box;\n}\n\nbody.uc-menu-push{\n  \ttransition: padding-left 1s, padding-right 1s;\n}\n\nbody.menu-opened{\n\toverflow: hidden;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .uc-side-menu-wrapper\n{\n  position:relative;\n}\n\n\n#uc_ue_side_menu_elementor_8649c87 .menu-right-open {\n\twidth: 300px;\n\ttop: 0;\n\tright: 0;\n\tmargin-right: 0px;\n\tmargin-left: 0px;\n\ttransition: 1s;\n\tz-index: 999999;\n\tposition: fixed;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-right-close {\n\twidth: 300px;\n\ttop: 0;\n\tright: 0;\n\tmargin-right: -300px;\n\ttransition: 1s;\n\tz-index: 1;\n\theight: 100%;\n\tposition: fixed;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-open {\n\twidth: 300px;\n\ttop: 0;\n\tleft: 0;\n\tmargin-right: 0px;\n\tmargin-left: 0px;\n\ttransition: 1s;\n\tz-index: 999999;\n\theight: 100%;\n\tposition: fixed;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-close {\n\twidth: 300px;\n\ttop: 0;\n\tleft: 0;\n\tmargin-left: -300px;\n\ttransition: 1s;\n\tz-index: 1;\n\theight: 100%;\n\tposition: fixed;\n}\n\n\t\n#uc_ue_side_menu_elementor_8649c87 .collapsed .uc-menu-item-pointer:after {\n\tcontent: \"\u25ba\";\n    display: inline-block;\n    background-repeat: no-repeat;\n    background-position: center;\n    background-size:contain;\n    margin:0px 15px;\n    vertical-align: middle;\n    font-size:10px;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .expanded .uc-menu-item-pointer:after {\n\tcontent: \"\u25bc\";\n    display: inline-block;\n    background-repeat: no-repeat;\n    background-position: center;\n    background-size:contain;\n    margin:0px 15px;\n    vertical-align: middle;\n    font-size:10px;\n}\n \n\t\n\n\n\n\n\n\n#uc_ue_side_menu_elementor_8649c87 .uc-side-menu-items\n{\n  position:relative;\n  height:100vh;\n  overflow-x: hidden;\n  transition:1s;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu\n{\n  cursor:pointer;\n  align-items:center;\n  justify-content:center;\n  transition: 0.4s ease;\n  position: relative;\n  line-height:1em;\n      \tdisplay: flex;\n  }\n\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu_toggle\n{\n  position: relative;\n  -webkit-box-flex: 0;\n  flex: none;\n  width: 100%;\n  height: 2px;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  transition: all 0.4s ease;\n}\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu_toggle:before,\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu_toggle:after {\n  content: '';\n  position: absolute;\n  z-index: 1;\n  top: -10px;\n  left: 0;\n  width: 100%;\n  height: 2px;\n  background: inherit;\n}\n\t\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu_toggle:after {\n  top: 10px;\n}\n\n\t\n\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu.uc-close-action .open_side_menu_toggle\n{\n  -webkit-transform: rotate(90deg);\n  transform: rotate(135deg);\n}\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu.uc-close-action .open_side_menu_toggle:before,\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu.uc-close-action .open_side_menu_toggle:after\n{\n  top: 0;\n  -webkit-transform: rotate(90deg);\n  transform: rotate(90deg);\n}\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu.uc-close-action .open_side_menu_toggle:after\n{\n opacity: 0;\n}\n#uc_ue_side_menu_elementor_8649c87 .open_side_menu.uc-close-action:hover .open_side_menu_toggle\n{\n  -webkit-transform: rotate(225deg);\n  transform: rotate(225deg);\n}\n\n\n#uc_ue_side_menu_elementor_8649c87 .uc-side-menu-title\n{\n  text-align:left;\n}\n\n.menu-left-open .uc-close-side-menu, .menu-right-open .uc-close-side-menu\n{\n  display:flex;\n  opacity:1;\n}\n\n.menu-left-close .uc-close-side-menu, .menu-right-close .uc-close-side-menu\n{\n  display:none;\n}\n\n.uc-close-side-menu\n{\n  line-height:1em;\n}\n\n.uc-close-side-menu svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-open .ue_side_menu_overlay, #uc_ue_side_menu_elementor_8649c87 .menu-right-open .ue_side_menu_overlay\n{\n  display:block;\n  opacity:1;\n  transition:1s;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-close .ue_side_menu_overlay, #uc_ue_side_menu_elementor_8649c87 .menu-right-close .ue_side_menu_overlay\n{\n  display:none;\n  opacity:0;\n  transition:1s;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .uc-close-side-menu\n{\n  position:absolute;\n  right:-50px;\n  cursor:pointer;\n  justify-content:center;\n  align-items:center;\n  z-index:1;\n}\n\n\n#uc_ue_side_menu_elementor_8649c87 .uc-side-menu-items ul\n{\n  padding:0px;\n  margin:0px;\n  list-style:none;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .uc-side-menu-items ul a\n{\n  display:block;\n  text-decoration:none;\n  position:relative;\n}\n\n\n#uc_ue_side_menu_elementor_8649c87 .sub-menu {\n    overflow: hidden;\n    list-style: none;\n    height: auto;\n    transition: 0.5s;\n  \t\n}\n\n#uc_ue_side_menu_elementor_8649c87 .side-menu-search-holder\n{\n  display:flex;\n  overflow:hidden;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .side-menu-search-holder input\n{\n  border:none;\n  border-radius:0px;\n  flex:1;\n  min-width: 0;\n  \n}\n#uc_ue_side_menu_elementor_8649c87 .side-menu-search-holder button\n{\n  border:none;\n  display:flex;\n  cursor:pointer;\n  align-items:center;\n  justify-content:center;\n  border-radius:0px;\n  flex-grow: 0;\n  flex-shrink: 0;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .side-menu-buttons\n{\n  display:flex;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .side-menu-button\n{\n  flex:1;\n  text-align:center;\n  text-decoration:none;\n}\n\n.side-menu-button\n{\n  font-size:12px;\n}\n\n\n#uc_ue_side_menu_elementor_8649c87  .ue_side_menu_overlay\n{\n  position:fixed;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n  transition:1s;\n  opacity:0;\n}\n\n\n\n\t\n\n  \n\n\n\n\n\n\n\n\n\/* On screens that are 768px *\/\n@media screen and (max-width: 768px) {\n  \n#uc_ue_side_menu_elementor_8649c87 .menu-right-open {\n\twidth: 379px;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-right-close {\n\twidth: 379px;\n\tmargin-right: -379px;\n\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-open {\n\twidth: 379px;\n\t\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-close {\n\twidth: 379px;\n\tmargin-left: -379px;\n\n}\n\n\/* On screens that are 420px *\/\n@media screen and (max-width: 420px) {\n  \n#uc_ue_side_menu_elementor_8649c87 .menu-right-open {\n\twidth: 300px;\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-right-close {\n\twidth: 300px;\n\tmargin-right: -300px;\n\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-open {\n\twidth: 300px;\n\t\n}\n\n#uc_ue_side_menu_elementor_8649c87 .menu-left-close {\n\twidth: 300px;\n\tmargin-left: -300px;\n}\n  \n}\n\n<\/style>\n\n<div id=\"uc_ue_side_menu_elementor_8649c87\" class=\"uc-side-menu-main-wrapper\" data-closeonbody=\"true\" data-push=\"false\" data-push-mobile=\"false\" data-expand=\"false\" data-clickable=\"false\" data-closeothers=\"false\">\n     \n      <div class=\"uc-menu-button-wrapper\" style=\"display:flex; justify-content:flex-end;\">\n          \n               <div class=\"open_side_menu\">\n                                    <i class='fas fa-bars'><\/i>\n                         \t   <\/div>\n          \n      <\/div>\n\t  \n      <div class=\"uc-side-menu-wrapper menu-right-close\" data-name=\"\" data-openonload=\"false\">\n        \t\t\t                        <div class=\"ue_side_menu_overlay\"><\/div>\n        \t\t            \n                        <div class=\"uc-close-side-menu\"><i class='fas fa-times'><\/i><\/div>\n                    \n          <div class=\"side-menu-holder\">\n              <div class=\"uc-side-menu-items\">\n                  <div class=\"uc-header\">\n                      \n                                            \n                  <\/div>\n                \n                                  \n                                    \n                  <div>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"41261\" class=\"elementor elementor-41261\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eefc061 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"eefc061\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-922aab5\" data-id=\"922aab5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fed1d9d elementor-widget elementor-widget-spacer\" data-id=\"fed1d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-047c7ba elementor-widget elementor-widget-image\" data-id=\"047c7ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"889\" src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/10\/LOGOS-AIU-06.png\" class=\"attachment-full size-full wp-image-74981\" alt=\"\" srcset=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/10\/LOGOS-AIU-06.png 2560w, https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/10\/LOGOS-AIU-06-300x104.png 300w, https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/10\/LOGOS-AIU-06-1024x356.png 1024w, https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/10\/LOGOS-AIU-06-768x267.png 768w, https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/10\/LOGOS-AIU-06-1536x534.png 1536w, https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/10\/LOGOS-AIU-06-2048x712.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c776bbc elementor-widget elementor-widget-spacer\" data-id=\"c776bbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c691b8 elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"3c691b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpml-elementor-ls\">\n<div\n\t role=\"navigation\" aria-label=\"Alternador de Idioma\" class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-dropdown js-wpml-ls-legacy-dropdown\">\n\t<ul>\n\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-pt wpml-ls-current-language wpml-ls-item-legacy-dropdown\">\n\t\t\t\t\t\t\t\t\t<a href=\"#\" hreflang=\"pt-pt\" lang=\"pt-pt\" class=\"js-wpml-ls-item-toggle wpml-ls-item-toggle\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-default\" aria-label=\"Portugu\u00eas \u2013 Language switcher, press tab to navigate to other languages\" title=\"Switch to Portugu\u00eas\">\n\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-pt.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">Portugu\u00eas<\/span><\/a>\n\n\t\t\t<ul id=\"wpml-ls-submenu-default\" class=\"wpml-ls-sub-menu\">\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/\" hreflang=\"en\" lang=\"en\" class=\"wpml-ls-link\" aria-label=\"Switch to English\" title=\"Switch to English\">\n\t\t\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/flags\/555526.png\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">English<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/es\/\" hreflang=\"es\" lang=\"es\" class=\"wpml-ls-link\" aria-label=\"Switch to Espa\u00f1ol\" title=\"Switch to Espa\u00f1ol\">\n\t\t\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">Espa\u00f1ol<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr wpml-ls-last-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/fr\/\" hreflang=\"fr\" lang=\"fr\" class=\"wpml-ls-link\" aria-label=\"Switch to Fran\u00e7ais\" title=\"Switch to Fran\u00e7ais\">\n\t\t\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=16\n            height=12\n    \/><span class=\"wpml-ls-native\">Fran\u00e7ais<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/li>\n\n\t<\/ul>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee91811 elementor-widget elementor-widget-spacer\" data-id=\"ee91811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef21d2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3ef21d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.aiu.edu\/aiu-login\/login.html\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Student Login<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83110d0 elementor-widget elementor-widget-spacer\" data-id=\"83110d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0f96f7 bdt-submenu-column-2 bdt-submenu-type-outer elementor-widget elementor-widget-bdt-vertical-menu\" data-id=\"a0f96f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-vertical-menu.default\">\n\t\t\t\t\t\t\t<div class=\"bdt-vertical-menu\" data-settings=\"{&quot;id&quot;:&quot;bdt-metismenu-a0f96f7&quot;,&quot;removeParentLink&quot;:&quot;no&quot;}\">\n\n\t\t\t\t\t\t\t\n\t\t<nav class=\"sidebar-nav\">\n\t\t\t<ul id=\"bdt-metismenu-a0f96f7\" class=\"metismenu \"><li class=\"bdt-menu-item\" class=\"sub-menu-columns\"><a href=\"#\"  class=\"has-arrow\">About AIU<\/a><ul><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/about-us\/\" class=\"\">Sobre n\u00f3s<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/general-information\/\" class=\"\">Informa\u00e7\u00f5es gerais<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/missionvision\/\" class=\"\">Miss\u00e3o e vis\u00e3o<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/faculty\/\" class=\"\">Docentes e funcion\u00e1rios<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/accreditation\/\" class=\"\">Acredita\u00e7\u00e3o<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/overview\/\" class=\"\">Vis\u00e3o geral<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/representations\/\" class=\"\">Representa\u00e7\u00f5es<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/school-of-business-and-economics\/\" class=\"\">Escola de Gest\u00e3o e Economia<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/school-of-science-and-engineering\/\" class=\"\">Escola de Ci\u00eancias e Engenharia<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/school-of-social-and-human-studies\/\" class=\"\">Escola de Estudos Sociais e Humanos<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/program-goals\/\" class=\"\">Objectivos do programa<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/unique-and-unrepeatable\/\" class=\"\">\u00danico e irrepet\u00edvel<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/andragogy-and-omniology\/\" class=\"\">Andragogia e Omniologia<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/academic-freedom-and-open-curriculum\/\" class=\"\">Liberdade acad\u00e9mica e curr\u00edculo aberto<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/holistic-and-asynchronous\/\" class=\"\">Hol\u00edstico e ass\u00edncrono<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/integral-culture\/\" class=\"\">Cultura Integral<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/71st-human-rights-anniversary\/\" class=\"\">71\u00ba Anivers\u00e1rio dos Direitos Humanos<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/contact-us\/\" class=\"\">Contactar-nos<\/a><\/li><\/ul><\/li><li class=\"bdt-menu-item\" class=\"sub-menu-columns\"><a href=\"#\"  class=\"has-arrow\">Press Room<\/a><ul><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/aiu-blog\/\" class=\"\">Blogue da AIU<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/aiu-news\/\" class=\"\">Not\u00edcias da AIU<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/aiu-testimonials\/\" class=\"\">Testemunhos<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/student-publications\/\" class=\"\">Publica\u00e7\u00f5es de estudantes<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/media-center\/\" class=\"\">Centro multim\u00e9dia<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/aiu-slides-collection\/\" class=\"\">Cole\u00e7\u00e3o de diapositivos da AIU<\/a><\/li><li class=\"bdt-menu-item\"><a target=\"_blank\" href=\"https:\/\/aiuvirtualgraduation.org\/\" class=\"\" rel=\"noopener\">Virtual Graduation<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/graduation-videos\/\" class=\"\">V\u00eddeos de gradua\u00e7\u00e3o da AIU<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/aiu-campus-mundi-all-editions\/\" class=\"\">AIU Campus Mundi todas as edi\u00e7\u00f5es<\/a><\/li><li class=\"bdt-menu-item\"><a target=\"_blank\" href=\"https:\/\/myaiu.tv\/\" class=\"\" rel=\"noopener\">AIU TV<\/a><\/li><li class=\"bdt-menu-item\"><a target=\"_blank\" href=\"https:\/\/myaiuradio.org\/\" class=\"\" rel=\"noopener\">AIU Radio<\/a><\/li><\/ul><\/li><li class=\"bdt-menu-item\" class=\"sub-menu-columns\"><a href=\"#\"  class=\"has-arrow\">Admissions &#038; Students<\/a><ul><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/student-experience\/\" class=\"\">Experi\u00eancia do estudante<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/community-social\/\" class=\"\">Comunidade Social<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/support-for-your-online-study\/\" class=\"\">Apoio ao seu estudo em linha<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/academic-resources\/\" class=\"\">Recursos acad\u00e9micos<\/a><\/li><li class=\"bdt-menu-item\"><a target=\"_blank\" href=\"https:\/\/www.aiu.edu\/university\/np\/conferences\/live-classes.html\" class=\"\">Live Classes<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/webinars-and-conferences\/\" class=\"\">Webinars e confer\u00eancias<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/distance-learning-and-online-courses\/\" class=\"\">Ensino \u00e0 dist\u00e2ncia e cursos em linha<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/career-center\/\" class=\"\">Centro de carreiras<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/admissions\/\" class=\"\">Admiss\u00f5es<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/tuition\/\" class=\"\">Propinas<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/associates-programs\/\" class=\"\">Programas para associados<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/bachelor-degree-programs\/\" class=\"\">Programas de licenciatura<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/masters-degree-programs\/\" class=\"\">Programas de mestrado<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/doctorate-degree-programs\/\" class=\"\">Programas de doutoramento<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/postdoctoral-research-program\/\" class=\"\">Programa de investiga\u00e7\u00e3o de p\u00f3s-doutoramento<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/overview\/\" class=\"\">Vis\u00e3o geral<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/aiu-testimonials\/\" class=\"\">Testemunhos<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/University\/np\/MyLifeIsASuccess\" class=\"\">AIU Success Stories<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/faqs\/\" class=\"\">FAQ<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/apply-online\/\" class=\"\">Candidatar-se online<\/a><\/li><li class=\"bdt-menu-item\"><a href=\"https:\/\/www.aiu.edu\/where-our-graduates-work\/\" class=\"\">Onde trabalham os nossos licenciados?<\/a><\/li><\/ul><\/li><\/ul>\t\t<\/nav>\n\n\t\t\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08b3b78 bdt-submenu-type-outer bdt-submenu-column-1 elementor-widget elementor-widget-bdt-vertical-menu\" data-id=\"08b3b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-vertical-menu.default\">\n\t\t\t\t\t\t\t<div class=\"bdt-vertical-menu\" data-settings=\"{&quot;id&quot;:&quot;bdt-metismenu-08b3b78&quot;,&quot;removeParentLink&quot;:&quot;no&quot;}\">\n\n\t\t\t\t\t\t\t\t\t<nav class=\"sidebar-nav\">\n\t\t\t<ul class=\"metismenu\" id=\"bdt-metismenu-08b3b78\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"has-arrow\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tResearch\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/research-areas\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tResearch Areas\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/aiu-reshaping-artificial-intelligence-in-higher-education\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tArtificial Intelligence\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/atlantic-international-university-webinars\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tWebinars\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/webinars-and-conferences\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tConferences &amp; Symposiums\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/aiu-dissertation-defense\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tThesis Dissertation Defense\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/academic-publication\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAcademic Publications\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/mentors-and-academic-advisors\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMentors &amp; Academic Advisors\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/grants-and-peer-review\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tGrants &amp; Peer Review\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/online-library\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tOnline Library\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/virtual-labs\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tVirtual Labs\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"has-arrow\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tVirtual Campus\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/aiu-virtual-campus\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tVirtual Campus\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/university\/np\/conferences\/archives.html\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tLive Classes\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/mini-courses\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMini Courses\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/features-and-tools\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tFeatures &amp; Tools\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/mobile-app\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMobile APP\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/social-media-center-aiu-link\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tSocial Media Center (AIU Link)\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/merlin-media-center\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMerlin Media Center\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/games-and-events\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tGames &amp; Events\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/online-library\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tOnline Library\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/curriculum-builder-tool\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCurriculum Builder\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/language-center\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tLanguage Center\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/site-builder\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tSite Builder\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/myaiu\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMyAIU\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"has-arrow\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPrograms Offered\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/areas-of-study\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAreas of Study\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/course-curriculum\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCourses and Curriculum\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/courses.aiu.edu\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tOpen Courses\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/register-for-a-program\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRegister for a Program\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/associates-programs\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAssociate Program\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/bachelor-degree-programs\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBachelor Program\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/masters-degree-programs\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tMaster's Program\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/doctorate-degree-programs\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tDoctoral Program\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/postdoctoral-research-program\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPostdoctoral Program\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"has-arrow\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAlumni\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/aiu-alumni-association\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tAlumni Association\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/graduation-videos\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tGraduation Videos\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/graduates\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tGraduates Directory\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/outstanding-students\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tOutstanding Students\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/University\/np\/MyLifeIsASuccess\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tSuccess Stories\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"bdt-menu-item\">\n\t\t\t\t\t\t\t<a class=\"\" href=\"https:\/\/www.aiu.edu\/sponsors\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tSponsors\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/nav>\n\t\t\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n                                    \n                                  \n                   <div><\/div>\n                \n                  \t\t\n                \n              <\/div>\n          <\/div>\n      <\/div>\n  \n<\/div>\n<!-- end Side Menu -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f70354c e-con-full e-flex e-con e-child\" data-id=\"f70354c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ed8403 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-tm-button\" data-id=\"6ed8403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www1.aiu.edu\/ApplyFormHTML\/ApplyFormAIN.aspx\" target=\"_blank\" class=\"tm-button-link tm-button style-flat tm-button-custom\" role=\"button\">\n\t\t\t\t\t\t<div class=\"button-content-wrapper\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"button-text\">APPLY NOW<\/span>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/header>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a0af1e elementor-section-height-min-height elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-items-middle elementor-section-column-vertical-align-stretch\" data-id=\"2a0af1e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a3c763\" data-id=\"0a3c763\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-144bfc2 elementor-widget elementor-widget-heading\" data-id=\"144bfc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00c1reas de investiga\u00e7\u00e3o<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d67587a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d67587a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-566e758 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"566e758\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c6ddc2\" data-id=\"9c6ddc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1befb62 elementor-widget elementor-widget-spacer\" data-id=\"1befb62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a07279 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"9a07279\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-018869f\" data-id=\"018869f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd3ac0e elementor-widget elementor-widget-heading\" data-id=\"bd3ac0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c1reas de investiga\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ec41dd7\" data-id=\"ec41dd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec3187 elementor-widget elementor-widget-text-editor\" data-id=\"eec3187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div>\n<div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">A melhor forma de obter o conhecimento \u00e9 a investiga\u00e7\u00e3o, e \u00e9 por isso que os programas da AIU incentivam os estudantes a demonstrarem compet\u00eancia atrav\u00e9s da aprendizagem independente, bem como da leitura e investiga\u00e7\u00e3o na sua \u00e1rea de estudo para atingirem os seus objectivos acad\u00e9micos.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--typographySection--LLeyX\">\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--typographyPropertyRowNarrow--WD0a9 inspect_panels--propertyRowNarrow--vTs-X inspect_panels--basePropertyRow--08faZ inspect_panels--_basePropertyRow--8NnfF\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27e6df0 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"27e6df0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6acf9c\" data-id=\"d6acf9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45df7fa elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"45df7fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-alimentos-sustentaveis-e-bioprodutos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Alimentos e bioprodutos sustent\u00e1veis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-biotecnologia\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Biotecnologia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-energia\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Energia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-inteligencia-artificial\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Intelig\u00eancia Artificial<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-ciencias-inovacao\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ci\u00eancia e inova\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-engenharia\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Engenharia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-biologia-genetica\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Biologia - Gen\u00e9tica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-neurociencias\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Neuroci\u00eancia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-comunidades-e-sustentabilidade\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comunidades e sustentabilidade<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-saude-e-bem-estar\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sa\u00fade e bem-estar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-factores-humanos-educacao-e-ciencias-psicologicas\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Factores Humanos, Educa\u00e7\u00e3o e Ci\u00eancias Psicol\u00f3gicas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-ciencias-da-atmosfera-e-do-espaco\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ci\u00eancias da Atmosfera e do Espa\u00e7o<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-computacao-dados-eletronica-e-detecao\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Computa\u00e7\u00e3o, dados, eletr\u00f3nica e dete\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/areas-de-investigacao-ecologia-ecossistemas-e-politica-ambiental\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ecologia, ecossistemas e pol\u00edtica ambiental<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e569ba8 elementor-widget elementor-widget-spacer\" data-id=\"e569ba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f4890bd\" data-id=\"f4890bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea8d3e6 elementor-widget elementor-widget-ucaddon_unlimited_grid\" data-id=\"ea8d3e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_unlimited_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Unlimited Grid -->\n\t\t<link id='fancybox-css' href='https:\/\/www.aiu.edu\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/fancybox3\/jquery.fancybox.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Unlimited Grid *\/\n\n#uc_unlimited_grid_elementor_ea8d3e6\n{\n  display:grid;\n  grid-auto-rows: 1fr;\n}\n\n.ue-btn\n{\n  text-decoration:none;\n  text-align:center;\n  transition:0.3s;\n}\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-overlay-link\n{\n  display:block;\n  position:absolute;\n  top:0px;\n  bottom:0px;\n  right:0px;\n  left:0px;\n}\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-item\n{\n  position:relative;\n  display:flex;\n  overflow:hidden;\n  background-size:cover;\n}\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-item-overlay\n{\n  position:absolute;\n  top:0;\n  right:0;\n  left:0;\n  bottom:0;\n  transition:0.3s;\n}\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-item-bg\n{\n  position:absolute;\n  top:0;\n  right:0;\n  left:0;\n  bottom:0;\n  transition:0.3s;\n  background-size:cover;\n}\n\n\n\t\n\n\n\n\n\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-graphic-element\n{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  overflow:hidden;\n}\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-graphic-element svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-graphic-element img\n{\n  display:block;\n}\n\n.ue-item-title\n{\n  font-size:21px;\n}\n\n#uc_unlimited_grid_elementor_ea8d3e6 .ue-item-content\n{\n  position:relative;\n  width:100%;\n}\n\n\n\n\t\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n  #uc_unlimited_grid_elementor_ea8d3e6 #uc_unlimited_grid_elementor_ea8d3e6_item1 .ue-item-bg\n  {\n    background-image:url(https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/Ecologically_Grown_Sustainable_Foods_1024x.webp);\n  }\n\n\n\n  #uc_unlimited_grid_elementor_ea8d3e6 #uc_unlimited_grid_elementor_ea8d3e6_item2 .ue-item-bg\n  {\n    background-image:url(https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/shutterstock_239731387-scaled.jpg);\n  }\n\n\n\n  #uc_unlimited_grid_elementor_ea8d3e6 #uc_unlimited_grid_elementor_ea8d3e6_item3 .ue-item-bg\n  {\n    background-image:url(https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/63632546_605.jpg);\n  }\n\n\n\n  #uc_unlimited_grid_elementor_ea8d3e6 #uc_unlimited_grid_elementor_ea8d3e6_item4 .ue-item-bg\n  {\n    background-image:url(https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/human-like-robot-and-artificial-intelligence-2022-01-06-00-25-53-utc.jpg);\n  }\n\n\n\n  #uc_unlimited_grid_elementor_ea8d3e6 #uc_unlimited_grid_elementor_ea8d3e6_item5 .ue-item-bg\n  {\n    background-image:url(https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/images.jpeg);\n  }\n\n\n\n  #uc_unlimited_grid_elementor_ea8d3e6 #uc_unlimited_grid_elementor_ea8d3e6_item6 .ue-item-bg\n  {\n    background-image:url(https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/types-of-engineers.jpg);\n  }\n\n\n\n  #uc_unlimited_grid_elementor_ea8d3e6 #uc_unlimited_grid_elementor_ea8d3e6_item7 .ue-item-bg\n  {\n    background-image:url(https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/neuroscience-and-motivation-what-you-need-know.png);\n  }\n\n\n\n\n\n<\/style>\n\n<div id=\"uc_unlimited_grid_elementor_ea8d3e6\" class=\"ue-unlimited-grid\">\n  <div id=\"uc_unlimited_grid_elementor_ea8d3e6_item1\" class=\"ue-item elementor-repeater-item-85d8f84\">\n  <div class=\"ue-item-bg\"><\/div>\n  <div class=\"ue-item-overlay\"><\/div>\n  \n    <div class=\"ue-item-content None\">\n                      <div class=\"ue-item-title\">Alimentos e bioprodutos sustent\u00e1veis<\/div>\n    <div class=\"ue-item-text\"><div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">Com uma popula\u00e7\u00e3o mundial em constante crescimento, a ci\u00eancia procura formas de otimizar os recursos de modo a oferecer alimentos de qualidade de uma forma amiga do ambiente. Atualmente, a investiga\u00e7\u00e3o centra-se na utiliza\u00e7\u00e3o eficiente dos recursos. O objetivo \u00e9 oferecer alimentos de boa qualidade, produzir muito mais alimentos utilizando menos terra e reduzir o desperd\u00edcio. Ao investigar como melhorar os processos de produ\u00e7\u00e3o alimentar, est\u00e1-se a melhorar a qualidade de vida do planeta e dos seus habitantes, ajudando este campo a combater as doen\u00e7as, a fome e, claro, a polui\u00e7\u00e3o.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div class=\"inspect_panels--panelTitle--fJsa9 text--fontPos11--rO47d text--_fontBase--VaHfk\">\n<div class=\"inspect_panels--panelCopyActionControls--xCSkr\"> <\/div>\n<\/div>\n<div>\n<div class=\"inspect_panels--typographySection--LLeyX\">\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--typographyPropertyRowNarrow--WD0a9 inspect_panels--propertyRowNarrow--vTs-X inspect_panels--basePropertyRow--08faZ inspect_panels--_basePropertyRow--8NnfF\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      <\/div>\n    \n  \n    \n    \n  <a class=\"ue-overlay-link\" href=\"https:\/\/www.aiu.edu\/research-areas-sustainable-food-bioproducts\/\"><\/a>\n  \n  \n  \n<\/div>\n<div id=\"uc_unlimited_grid_elementor_ea8d3e6_item2\" class=\"ue-item elementor-repeater-item-690ace0\">\n  <div class=\"ue-item-bg\"><\/div>\n  <div class=\"ue-item-overlay\"><\/div>\n  \n    <div class=\"ue-item-content None\">\n                      <div class=\"ue-item-title\">Biotecnologia<\/div>\n    <div class=\"ue-item-text\"><div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">O que \u00e9 mais importante do que a vida? A biotecnologia \u00e9 a ci\u00eancia da vida. O seu primeiro objetivo \u00e9 a investiga\u00e7\u00e3o de diferentes tecnologias e organismos vivos para criar novas solu\u00e7\u00f5es para uso humano espec\u00edfico.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--typographySection--LLeyX\">\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--typographyPropertyRowNarrow--WD0a9 inspect_panels--propertyRowNarrow--vTs-X inspect_panels--basePropertyRow--08faZ inspect_panels--_basePropertyRow--8NnfF\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      <\/div>\n    \n  \n    \n    \n  <a class=\"ue-overlay-link\" href=\"https:\/\/www.aiu.edu\/research-areas-biotechnology\/\"><\/a>\n  \n  \n  \n<\/div>\n<div id=\"uc_unlimited_grid_elementor_ea8d3e6_item3\" class=\"ue-item elementor-repeater-item-a40b6a2\">\n  <div class=\"ue-item-bg\"><\/div>\n  <div class=\"ue-item-overlay\"><\/div>\n  \n    <div class=\"ue-item-content None\">\n                      <div class=\"ue-item-title\">Energia<\/div>\n    <div class=\"ue-item-text\"><div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">A energia \u00e9 a base do nosso quotidiano. De facto, \u00e9 o sol que dita o nosso ritmo di\u00e1rio. Com a evolu\u00e7\u00e3o, o homem criou as suas pr\u00f3prias fontes de energia que lhe permitem continuar a sua rotina quando as fontes de energia naturais n\u00e3o est\u00e3o dispon\u00edveis.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--typographySection--LLeyX\">\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--typographyPropertyRowNarrow--WD0a9 inspect_panels--propertyRowNarrow--vTs-X inspect_panels--basePropertyRow--08faZ inspect_panels--_basePropertyRow--8NnfF\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      <\/div>\n    \n  \n    \n    \n  <a class=\"ue-overlay-link\" href=\"https:\/\/www.aiu.edu\/research-areas-energy\/\"><\/a>\n  \n  \n  \n<\/div>\n<div id=\"uc_unlimited_grid_elementor_ea8d3e6_item4\" class=\"ue-item elementor-repeater-item-c400ec5\">\n  <div class=\"ue-item-bg\"><\/div>\n  <div class=\"ue-item-overlay\"><\/div>\n  \n    <div class=\"ue-item-content None\">\n                      <div class=\"ue-item-title\">Intelig\u00eancia Artificial<\/div>\n    <div class=\"ue-item-text\"><div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">A procura constante de criar sistemas inteligentes levou os investigadores \u00e0 conce\u00e7\u00e3o da Intelig\u00eancia Artificial, que procura criar sistemas para lidar com tarefas complexas no dia a dia, permitindo \u00e0s organiza\u00e7\u00f5es tomar melhores decis\u00f5es, melhorar processos, reduzir o erro humano e aumentar a velocidade e a precis\u00e3o dos processos.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      <\/div>\n    \n  \n    \n    \n  <a class=\"ue-overlay-link\" href=\"https:\/\/www.aiu.edu\/research-areas-artificial-intelligence\/\"><\/a>\n  \n  \n  \n<\/div>\n<div id=\"uc_unlimited_grid_elementor_ea8d3e6_item5\" class=\"ue-item elementor-repeater-item-357b4ea\">\n  <div class=\"ue-item-bg\"><\/div>\n  <div class=\"ue-item-overlay\"><\/div>\n  \n    <div class=\"ue-item-content None\">\n                      <div class=\"ue-item-title\">Ci\u00eancia e inova\u00e7\u00e3o<\/div>\n    <div class=\"ue-item-text\"><div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">A ci\u00eancia e a inova\u00e7\u00e3o procuram dia a dia, atrav\u00e9s da investiga\u00e7\u00e3o, gerar novos conhecimentos que permitam \u00e0 humanidade promover a sua prosperidade e o seu futuro, resolvendo e contribuindo para todos os aspectos da vida, desde as doen\u00e7as aos avan\u00e7os no espa\u00e7o.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      <\/div>\n    \n  \n    \n    \n  <a class=\"ue-overlay-link\" href=\"https:\/\/www.aiu.edu\/research-areas-sciences-innovation\/\"><\/a>\n  \n  \n  \n<\/div>\n<div id=\"uc_unlimited_grid_elementor_ea8d3e6_item6\" class=\"ue-item elementor-repeater-item-bbc7e94\">\n  <div class=\"ue-item-bg\"><\/div>\n  <div class=\"ue-item-overlay\"><\/div>\n  \n    <div class=\"ue-item-content None\">\n                      <div class=\"ue-item-title\">Engenharia<\/div>\n    <div class=\"ue-item-text\"><div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">As pessoas trabalham o seu engenho para tornar o mundo um lugar melhor, esta \u00e9 a tarefa dos engenheiros com os seus projectos e investiga\u00e7\u00e3o. A engenharia \u00e9 fundamental na investiga\u00e7\u00e3o, desenvolvimento e produ\u00e7\u00e3o de cada produto, de cada dispositivo...<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--typographySection--LLeyX\">\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--typographyPropertyRowNarrow--WD0a9 inspect_panels--propertyRowNarrow--vTs-X inspect_panels--basePropertyRow--08faZ inspect_panels--_basePropertyRow--8NnfF\"> <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      <\/div>\n    \n  \n    \n    \n  <a class=\"ue-overlay-link\" href=\"https:\/\/www.aiu.edu\/research-areas-engineering\/\"><\/a>\n  \n  \n  \n<\/div>\n<div id=\"uc_unlimited_grid_elementor_ea8d3e6_item7\" class=\"ue-item elementor-repeater-item-8eaa2ed\">\n  <div class=\"ue-item-bg\"><\/div>\n  <div class=\"ue-item-overlay\"><\/div>\n  \n    <div class=\"ue-item-content None\">\n                      <div class=\"ue-item-title\">Neuroci\u00eancia<\/div>\n    <div class=\"ue-item-text\"><div class=\"raw_components--panel--YDedw inspect_panels--inspectionPanel--o9CfO\" tabindex=\"-1\">\n<div>\n<div class=\"inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--propertyRowContent--qvupJ inspect_panels--copyableRow--ecLWm inspect_panels--highlightRow--BeZQJ\">\n<div class=\"inspect_panels--contentProperty--McE5j text--fontPos11--rO47d text--_fontBase--VaHfk ellipsis--ellipsisAfter8Lines--2JTeB ellipsis--_ellipsisAfterNLines--5f-ox\" dir=\"auto\">Conhecer o c\u00e9rebro humano, prever poss\u00edveis complica\u00e7\u00f5es no desenvolvimento e curar doen\u00e7as derivadas de problemas no sistema nervoso s\u00e3o as principais motiva\u00e7\u00f5es para a investiga\u00e7\u00e3o em neuroci\u00eancias, que s\u00e3o definitivamente fundamentais para o desenvolvimento humano.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n      <\/div>\n    \n  \n    \n    \n  <a class=\"ue-overlay-link\" href=\"https:\/\/www.aiu.edu\/research-areas-neuroscience\/\"><\/a>\n  \n  \n  \n<\/div>\n\n<\/div>\n<!-- end Unlimited Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fc5a34 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"9fc5a34\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05f1dc8\" data-id=\"05f1dc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d505e3 elementor-widget elementor-widget-template\" data-id=\"0d505e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<footer data-elementor-type=\"footer\" data-elementor-id=\"3023\" class=\"elementor elementor-3023\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f1fc161 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"f1fc161\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b16bbab\" data-id=\"b16bbab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5be41aa elementor-widget elementor-widget-ucaddon_post_carousel\" data-id=\"5be41aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Carousel -->\n\t\t<link id='owl-carousel-css' href='https:\/\/www.aiu.edu\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='lity-css' href='https:\/\/www.aiu.edu\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/lity\/lity.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Post Carousel *\/\n\n#uc_post_carousel_elementor_5be41aa *{\n  box-sizing:border-box;\n}\n#uc_post_carousel_elementor_5be41aa{\n  position:relative;\n}\n.uc_post_title{\n  font-size:21px;\n}\n\n#uc_post_carousel_elementor_5be41aa .ue-item\n{\n  transition:0.3s;\n}\n\n#uc_post_carousel_elementor_5be41aa .uc_image_carousel_placeholder\n{\n  position:relative;\n}\n\n#uc_post_carousel_elementor_5be41aa .ue_pos_carousel_image_overlay\n{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n  transition:0.3s;\n}\n\n#uc_post_carousel_elementor_5be41aa .uc_carousel_item\n{\n  overflow:hidden;\n}\n\n#uc_post_carousel_elementor_5be41aa .owl-nav .owl-prev{\n    position:absolute;\n    display:inline-block;\n    text-align:center;\n}\n#uc_post_carousel_elementor_5be41aa .owl-nav .owl-next{\n  position:absolute;\n  display:inline-block;\n  text-align:center;\n}\n\n\n#uc_post_carousel_elementor_5be41aa .owl-dots {\noverflow:hidden;\ndisplay:flex !important;\n}\n\n#uc_post_carousel_elementor_5be41aa .owl-dot {\nborder-radius:50%;\ndisplay:inline-block;\n}\n\n\n\n#uc_post_carousel_elementor_5be41aa .uc_more_btn{\n\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n}  \n\n#uc_post_carousel_elementor_5be41aa .uc_image_carousel_placeholder img\n{\n  display:block;\n  width:100%;\n}\n\n#uc_post_carousel_elementor_5be41aa .uc_image_carousel_content \n{\n  display:flex;\n  flex-direction:column;\n}\n\n\n\t\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n#uc_post_carousel_elementor_5be41aa .ue-meta-data\n{\n  \n  display:flex;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_carousel_elementor_5be41aa .ue-grid-item-meta-data\n{\n      display:inline-flex;\n      align-items:center;\n}\n\n.ue-grid-item-meta-data\n{\n  font-size:12px;\n}\n\n#uc_post_carousel_elementor_5be41aa .ue-grid-item-meta-data-icon\n{\n  line-height:1em;\n}\n\n#uc_post_carousel_elementor_5be41aa .ue-grid-item-meta-data-icon svg\n{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_carousel_elementor_5be41aa .ue-debug-meta\n{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n<\/style>\n\n<div class=\"uc_overlay_image_carousel\">\n   <div class=\"uc_carousel owl-carousel owl-theme uc-items-wrapper \" data-custom-sethtml=\"true\"  data-id=\"\" id=\"uc_post_carousel_elementor_5be41aa\" >\n   \t\t<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/09\/Social-Media-Marketing2-1-1-768x403.png\" alt=\"Social Media Marketing Online \" width=\"768\" height=\"403\" title=\"\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n          \n                  \n          \n          \n          \n        <a href=\"https:\/\/www.aiu.edu\/pt-pt\/program\/mestrado-em-marketing-nas-redes-sociais\/\"><div class=\"uc_post_title\">Mestrado em Marketing nas Redes Sociais<\/div><\/a>        \n          \n          \n         \n         <div class=\"ue-meta-data\">\n                        \n                        \n            \n                        \n                        \n                       \n               \n\n            \n          <\/div> \n          \n          \n          \n          \n          \n                \n        <\/div>\n    \n                <div class=\"ue-item-btn-holder\">\n        <a class=\"uc_more_btn\" href=\"https:\/\/www.aiu.edu\/pt-pt\/program\/mestrado-em-marketing-nas-redes-sociais\/\">More Details<\/a>\n        <\/div>\n          <\/div>\n  <\/div>\n<div class=\"uc_image_carousel_container_holder uc_carousel_item ue-item\">\n  \n    <div class=\"uc_image_carousel_placeholder\">\n                 \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2022\/12\/Bachelor-in-Artificial-Intelligence-768x400.jpg\" alt=\"Bachelor in Artificial Intelligence\" width=\"768\" height=\"400\" title=\"\"> \n        \t\n        <div class=\"ue_pos_carousel_image_overlay\"><\/div>\n          <\/div>\n  \n  \n    <div class=\"uc_image_carousel_content\" >\n        <div>\n          \n          \n                  \n          \n          \n          \n        <a href=\"https:\/\/www.aiu.edu\/pt-pt\/program\/licenciatura-em-inteligencia-artificial\/\"><div class=\"uc_post_title\">Licenciatura em Intelig\u00eancia Artificial<\/div><\/a>        \n          \n          \n         \n         <div class=\"ue-meta-data\">\n                        \n                        \n            \n                        \n                        \n                       \n               \n\n            \n          <\/div> \n          \n          \n          \n          \n          \n                \n        <\/div>\n    \n                <div class=\"ue-item-btn-holder\">\n        <a class=\"uc_more_btn\" href=\"https:\/\/www.aiu.edu\/pt-pt\/program\/licenciatura-em-inteligencia-artificial\/\">More Details<\/a>\n        <\/div>\n          <\/div>\n  <\/div>\n\n   <\/div>\t\n<\/div>\n\n\n<!-- end Post Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a6df75 elementor-section-full_width elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"3a6df75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-caa34be\" data-id=\"caa34be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-234fc2f e-flex e-con-boxed e-con e-parent\" data-id=\"234fc2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d891721 elementor-widget elementor-widget-image\" data-id=\"d891721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"230\" src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2025\/07\/footer-updated-logo.png\" class=\"attachment-large size-large wp-image-171174\" alt=\"footer-updated-logo\" srcset=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/2025\/07\/footer-updated-logo.png 560w, https:\/\/www.aiu.edu\/wp-content\/uploads\/2025\/07\/footer-updated-logo-300x123.png 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cadeb87 elementor-section-gap-beside-no footer_links elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"cadeb87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-50fb8d7\" data-id=\"50fb8d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa10917 elementor-widget elementor-widget-tm-heading\" data-id=\"aa10917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-modern-heading\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<h4 class=\"heading-primary elementor-heading-title\">Contact Information<\/h4>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f39622 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7f39622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.aiu.edu\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact Us <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8953e0 elementor-widget elementor-widget-text-editor\" data-id=\"e8953e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.aiu.edu\/register-for-a-program\/\">Register for a Program<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ffb6a6 elementor-widget elementor-widget-tm-heading\" data-id=\"5ffb6a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-modern-heading\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<h4 class=\"heading-primary elementor-heading-title\">Atlantic International University<\/h4>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e28aff8 elementor-widget elementor-widget-text-editor\" data-id=\"e28aff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>900 Fort Street Mall, #905, Honolulu, HI 96813<\/p><ul><li><a href=\"tel:8009930066\">800-993-0066 (Toll-Free, US)<\/a><\/li><li><a href=\"tel:8089249567\">808-924-9567 (International)<\/a><\/li><li><a href=\"tel:8089472488\">808-947-2488 (Fax)<\/a><\/li><\/ul><p><a style=\"font-weight: bold;\" href=\"mailto:info@aiu.edu\">info@aiu.edu<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a56fe9d footer-social elementor-widget elementor-widget-tm-social-networks\" data-id=\"a56fe9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-social-networks.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-social-networks style-large-icons layout-inline\">\n\t\t\t<ul class=\"list\">\t\t\t\t<li class=\"item elementor-repeater-item-a4ebc41\">\n\t\t\t\t\t<a class=\"link hint--bounce hint--top hint--white\" aria-label=\"X\" href=\"https:\/\/x.com\/aiu_university\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<i class=\"link-icon fa-brands fa-x-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"item elementor-repeater-item-3a62d63\">\n\t\t\t\t\t<a class=\"link hint--bounce hint--top hint--white\" aria-label=\"Facebook\" href=\"https:\/\/www.facebook.com\/AIU.University\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<i class=\"link-icon fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"item elementor-repeater-item-5840c98\">\n\t\t\t\t\t<a class=\"link hint--bounce hint--top hint--white\" aria-label=\"Instagram\" href=\"https:\/\/www.instagram.com\/atlanticinteruniversity\/\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<i class=\"link-icon fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"item elementor-repeater-item-ecbdfc2\">\n\t\t\t\t\t<a class=\"link hint--bounce hint--top hint--white\" aria-label=\"Youtube Chanel\" href=\"https:\/\/www.youtube.com\/user\/AIUvideos\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<i class=\"link-icon fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"item elementor-repeater-item-730ad8d\">\n\t\t\t\t\t<a class=\"link hint--bounce hint--top hint--white\" aria-label=\"Linkedin\" href=\"https:\/\/www.linkedin.com\/school\/atlantic-international-university\/\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<i class=\"link-icon fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-9be261a\" data-id=\"9be261a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af576c2 elementor-widget elementor-widget-tm-heading\" data-id=\"af576c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-modern-heading\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<h4 class=\"heading-primary elementor-heading-title\">Programs<\/h4>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffbbdc4 elementor-widget elementor-widget-text-editor\" data-id=\"ffbbdc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/www.aiu.edu\/bachelor-degree-programs\/\">Bachelor Degree Programs<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/masters-degree-programs\">Masters Degree Programs<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/doctorate-degree-programs\">Doctoral Degree Programs<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/areas-of-study\/\">Areas of Study<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/course-curriculum\/\">Course &amp; Curriculum<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-d87dc44\" data-id=\"d87dc44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23572eb elementor-widget elementor-widget-tm-heading\" data-id=\"23572eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-modern-heading\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<h4 class=\"heading-primary elementor-heading-title\">Student Resources <\/h4>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a0355c elementor-widget elementor-widget-text-editor\" data-id=\"1a0355c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/www.aiu.edu\/online-library\/\">Online Library<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/aiu-virtual-campus\/\">Virtual Campus<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/aiu-testimonials\/\">Student Testimonials<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/aiu-blog\/\">Blogs<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/media-center\">Media Center<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/mini-courses\">Mini Courses<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-610393d\" data-id=\"610393d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f3ef8e elementor-widget elementor-widget-tm-heading\" data-id=\"7f3ef8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-modern-heading\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<h4 class=\"heading-primary elementor-heading-title\">Admissions<\/h4>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2687c87 elementor-widget elementor-widget-text-editor\" data-id=\"2687c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/www.aiu.edu\/apply-online\">Apply Online<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/tuition\/\">Tuition<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/admissions\/\">Admission Requirements<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/faculty\/\">Faculty &amp; Staff<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-7ef6ba0\" data-id=\"7ef6ba0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b42233 elementor-widget elementor-widget-tm-heading\" data-id=\"9b42233\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-modern-heading\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<h4 class=\"heading-primary elementor-heading-title\">About AIU<\/h4>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-823538c elementor-widget elementor-widget-text-editor\" data-id=\"823538c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/www.aiu.edu\/missionvision\/\">Mission &amp; Vision<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/71st-human-rights-anniversary\">Human Rights<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/research-areas-artificial-intelligence\/\">Artificial Intelligence<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/sponsors\">Sponsors<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/general-information\/\">General Information<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/accreditation\/\">Accreditation<\/a><\/li><li><a href=\"https:\/\/www.aiu.edu\/privacy-policy\">Privacy Policy<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-829a1e5 elementor-section-gap-beside-no elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"829a1e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d7bc8c2\" data-id=\"d7bc8c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba09c05 footer_wpml elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"ba09c05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpml-elementor-ls\">\n<div role=\"navigation\" aria-label=\"Alternador de Idioma\" class=\"wpml-ls-statics-footer wpml-ls wpml-ls-legacy-list-horizontal\">\n\t<ul><li class=\"wpml-ls-slot-footer wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/\" hreflang=\"en\" lang=\"en\" class=\"wpml-ls-link\" aria-label=\"Switch to Ingl\u00eas\" title=\"Switch to Ingl\u00eas\">\n\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/uploads\/flags\/555526.png\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=15\n            height=10\n    \/><span class=\"wpml-ls-display\">Ingl\u00eas<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-footer wpml-ls-item wpml-ls-item-es wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/es\/\" hreflang=\"es\" lang=\"es\" class=\"wpml-ls-link\" aria-label=\"Switch to Espanhol\" title=\"Switch to Espanhol\">\n\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=15\n            height=10\n    \/><span class=\"wpml-ls-display\">Espanhol<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-footer wpml-ls-item wpml-ls-item-pt-pt wpml-ls-current-language wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/pt-pt\/\" hreflang=\"pt-pt\" lang=\"pt-pt\" class=\"wpml-ls-link\" aria-current=\"page\" aria-label=\"Switch to Portugu\u00eas\" title=\"Switch to Portugu\u00eas\">\n\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-pt.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=15\n            height=10\n    \/><span class=\"wpml-ls-native\">Portugu\u00eas<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-footer wpml-ls-item wpml-ls-item-fr wpml-ls-last-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/www.aiu.edu\/fr\/\" hreflang=\"fr\" lang=\"fr\" class=\"wpml-ls-link\" aria-label=\"Switch to Franc\u00eas\" title=\"Switch to Franc\u00eas\">\n\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/www.aiu.edu\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=15\n            height=10\n    \/><span class=\"wpml-ls-display\">Franc\u00eas<\/span><\/a>\n\t\t\t<\/li><\/ul>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb859bd elementor-widget elementor-widget-tm-heading\" data-id=\"bb859bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tm-modern-heading\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<div class=\"heading-primary elementor-heading-title\">Copyright \u00a9 1979-2026 Atlantic International University.\n\nAll rights reserved.<\/div>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/footer>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c1reas de investiga\u00e7\u00e3o \u00c1reas de investiga\u00e7\u00e3o A melhor forma de obter o conhecimento \u00e9 a investiga\u00e7\u00e3o, e \u00e9 por isso que os programas da AIU incentivam os estudantes a demonstrarem compet\u00eancia atrav\u00e9s da aprendizagem independente, bem como da leitura e investiga\u00e7\u00e3o na sua \u00e1rea de estudo para atingirem os seus objectivos acad\u00e9micos. Alimentos e bioprodutos sustent\u00e1veis Biotecnologia Energia Intelig\u00eancia Artificial Ci\u00eancia e inova\u00e7\u00e3o Engenharia Biologia &#8211; Gen\u00e9tica Neuroci\u00eancia Comunidades e sustentabilidade Sa\u00fade e bem-estar Factores Humanos, Educa\u00e7\u00e3o e Ci\u00eancias Psicol\u00f3gicas Ci\u00eancias da Atmosfera e do Espa\u00e7o Computa\u00e7\u00e3o, dados, eletr\u00f3nica e dete\u00e7\u00e3o Ecologia, ecossistemas e pol\u00edtica ambiental Alimentos e bioprodutos sustent\u00e1veis Com uma popula\u00e7\u00e3o mundial em constante crescimento, a ci\u00eancia procura formas de otimizar os recursos de modo a oferecer alimentos de qualidade de uma forma amiga do ambiente. Atualmente, a investiga\u00e7\u00e3o centra-se na utiliza\u00e7\u00e3o eficiente dos recursos. O objetivo \u00e9 oferecer alimentos de boa qualidade, produzir muito mais alimentos utilizando menos terra e reduzir o desperd\u00edcio. Ao investigar como melhorar os processos de produ\u00e7\u00e3o alimentar, est\u00e1-se a melhorar a qualidade de vida do planeta e dos seus habitantes, ajudando este campo a combater as doen\u00e7as, a fome e, claro, a polui\u00e7\u00e3o. Biotecnologia O que \u00e9 mais importante do que a vida? A biotecnologia \u00e9 a ci\u00eancia da vida. O seu primeiro objetivo \u00e9 a investiga\u00e7\u00e3o de diferentes tecnologias e organismos vivos para criar novas solu\u00e7\u00f5es para uso humano espec\u00edfico. Energia A energia \u00e9 a base do nosso quotidiano. De facto, \u00e9 o sol que dita o nosso ritmo di\u00e1rio. Com a evolu\u00e7\u00e3o, o homem criou as suas pr\u00f3prias fontes de energia que lhe permitem continuar a sua rotina quando as fontes de energia naturais n\u00e3o est\u00e3o dispon\u00edveis. Intelig\u00eancia Artificial A procura constante de criar sistemas inteligentes levou os investigadores \u00e0 conce\u00e7\u00e3o da Intelig\u00eancia Artificial, que procura criar sistemas para lidar com tarefas complexas no dia a dia, permitindo \u00e0s organiza\u00e7\u00f5es tomar melhores decis\u00f5es, melhorar processos, reduzir o erro humano e aumentar a velocidade e a precis\u00e3o dos processos. Ci\u00eancia e inova\u00e7\u00e3o A ci\u00eancia e a inova\u00e7\u00e3o procuram dia a dia, atrav\u00e9s da investiga\u00e7\u00e3o, gerar novos conhecimentos que permitam \u00e0 humanidade promover a sua prosperidade e o seu futuro, resolvendo e contribuindo para todos os aspectos da vida, desde as doen\u00e7as aos avan\u00e7os no espa\u00e7o. Engenharia As pessoas trabalham o seu engenho para tornar o mundo um lugar melhor, esta \u00e9 a tarefa dos engenheiros com os seus projectos e investiga\u00e7\u00e3o. A engenharia \u00e9 fundamental na investiga\u00e7\u00e3o, desenvolvimento e produ\u00e7\u00e3o de cada produto, de cada dispositivo&#8230; Neuroci\u00eancia Conhecer o c\u00e9rebro humano, prever poss\u00edveis complica\u00e7\u00f5es no desenvolvimento e curar doen\u00e7as derivadas de problemas no sistema nervoso s\u00e3o as principais motiva\u00e7\u00f5es para a investiga\u00e7\u00e3o em neuroci\u00eancias, que s\u00e3o definitivamente fundamentais para o desenvolvimento humano.<\/p>\n","protected":false},"author":130,"featured_media":74856,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-98117","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/pages\/98117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/users\/130"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/comments?post=98117"}],"version-history":[{"count":0,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/pages\/98117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/media\/74856"}],"wp:attachment":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/media?parent=98117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}