{"id":91137,"date":"2022-09-14T13:02:40","date_gmt":"2022-09-14T17:02:40","guid":{"rendered":"https:\/\/www.aiu.edu\/program\/doutoramento-em-design-e-construcao-sustentavel\/"},"modified":"2024-03-19T18:46:04","modified_gmt":"2024-03-19T22:46:04","slug":"doutoramento-em-design-e-construcao-sustentavel","status":"publish","type":"program","link":"https:\/\/www.aiu.edu\/pt-pt\/program\/doutoramento-em-design-e-construcao-sustentavel\/","title":{"rendered":"Doutoramento em Design e Constru\u00e7\u00e3o Sustent\u00e1vel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":69674,"parent":0,"menu_order":0,"template":"","majors":[4435],"school":[4541],"degree":[4545],"aiu_macro":[],"related_majors":[],"related_subjects":[],"class_list":["post-91137","program","type-program","status-publish","has-post-thumbnail","hentry","majors-sustainable-design-and-construction-pt-pt","school-escola-de-ciencias-e-engenharia","degree-programa-de-doutorado"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/program\/91137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":0,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/program\/91137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/media\/69674"}],"wp:attachment":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/media?parent=91137"}],"wp:term":[{"taxonomy":"majors","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/majors?post=91137"},{"taxonomy":"school","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/school?post=91137"},{"taxonomy":"degree","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/degree?post=91137"},{"taxonomy":"aiu_macro","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/aiu_macro?post=91137"},{"taxonomy":"related_majors","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/related_majors?post=91137"},{"taxonomy":"related_subjects","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/related_subjects?post=91137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}