{"id":91260,"date":"2022-09-13T06:52:29","date_gmt":"2022-09-13T10:52:29","guid":{"rendered":"https:\/\/www.aiu.edu\/program\/mestrado-em-arqueologia-ma\/"},"modified":"2022-09-13T06:52:29","modified_gmt":"2022-09-13T10:52:29","slug":"mestrado-em-arqueologia-ma","status":"publish","type":"program","link":"https:\/\/www.aiu.edu\/pt-pt\/program\/mestrado-em-arqueologia-ma\/","title":{"rendered":"Mestrado em Arqueologia (MA)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":68514,"parent":0,"menu_order":0,"template":"","majors":[4399],"school":[4538],"degree":[4547],"aiu_macro":[],"related_majors":[],"related_subjects":[],"class_list":["post-91260","program","type-program","status-publish","has-post-thumbnail","hentry","majors-archeology-pt-pt","school-escola-de-negocios-e-economia","degree-programa-de-mestrado"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/program\/91260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/types\/program"}],"version-history":[{"count":0,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/program\/91260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/media\/68514"}],"wp:attachment":[{"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/media?parent=91260"}],"wp:term":[{"taxonomy":"majors","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/majors?post=91260"},{"taxonomy":"school","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/school?post=91260"},{"taxonomy":"degree","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/degree?post=91260"},{"taxonomy":"aiu_macro","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/aiu_macro?post=91260"},{"taxonomy":"related_majors","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/related_majors?post=91260"},{"taxonomy":"related_subjects","embeddable":true,"href":"https:\/\/www.aiu.edu\/pt-pt\/wp-json\/wp\/v2\/related_subjects?post=91260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}